{"id":9698,"date":"2018-10-29T11:17:15","date_gmt":"2018-10-29T16:17:15","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=9698"},"modified":"2025-06-02T11:33:19","modified_gmt":"2025-06-02T16:33:19","slug":"surebuilt-anade-servicios-de-ingenieria-de-tilt-up","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/2018\/10\/29\/surebuilt-anade-servicios-de-ingenieria-de-tilt-up\/","title":{"rendered":"SUREBUILT A\u00d1ADE SERVICIOS DE INGENIER\u00cdA DE TILT-UP"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/2018\/10\/29\/surebuilt-adding-tilt-up-engineering-services\/\"><strong>English<\/strong><\/a> | Translation Sponsored by <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Nox-Crete Products Group<\/a><\/p>\n<\/div>\n<p><strong>En respuesta a la creciente demanda<\/strong> de contratistas por sus productos de tilt-up, SureBuilt est\u00e1 a\u00f1adiendo servicios de ingenier\u00eda para soporte de aplicaci\u00f3n de proyectos. Tom Fahey, propietario y CEO, anunci\u00f3 que estos servicios se localizar\u00e1n en el nuevo almac\u00e9n y planta de manufactura de SureBuilt en 1851 Massaro Avenue en Tampa, FL.<\/p>\n<p>Los servicios, llamados servicios de ingenier\u00eda SureBuilt, ser\u00e1n gestionados por Dave Reardon, profesional de la industria con m\u00e1s de 30 a\u00f1os de experiencia en la construcci\u00f3n de concreto, incluyendo experiencia en tilt-up en el mercado de Florida. \u00c9l dirigir\u00e1 a un equipo de dise\u00f1adores excepcionalmente calificados que ya est\u00e1n familiarizados con la especificaci\u00f3n, ingenier\u00eda y pr\u00e1cticas de construcci\u00f3n de tilt-up.<\/p>\n<p>Dave manifest\u00f3, \u201cla industria siempre busca ideas nuevas, productos innovadores y servicios de valor a\u00f1adido. SureBuilt busca introducir estos tipos de ideas que cambian la industria mediante la oferta de servicios de ingenier\u00eda mejorados. Nuestra misi\u00f3n es ofrecer al contratista y al proveedor las herramientas para mejorar y agilizar el proceso de construcci\u00f3n\u201d.<\/p>\n<p>Con ese fin, hemos establecido una nueva l\u00ednea de producci\u00f3n de riostras para tilt-up de tama\u00f1os 42\u2019 y 52\u2019 para satisfacer la creciente demanda. Esta l\u00ednea nos ayudar\u00e1 a lograr y mantener la calidad requerida en un ambiente de alta producci\u00f3n. Por supuesto, todas las riostras de tilt-up de SureBuilt cumplen con los lineamientos m\u00e1s recientes de la TCA y AISC.<\/p>\n<p>Dave a\u00f1adi\u00f3, \u201cnuestro objetivo es apoyar a nuestra distribuci\u00f3n en sus esfuerzos de ofrecer productos y servicios que beneficien al contratista. Nuestros esfuerzos colectivos siempre deben garantizar que cada proyecto sea un \u00e9xito\u201d.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre los servicios de ingenier\u00eda de SureBuilt, llame a Dave Reardon al 813-606-5727 o env\u00ede un correo electr\u00f3nico a dreardon@surebuilt-usa.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">English | Translation Sponsored by Nox-Crete Products Group En respuesta a la creciente demanda de contratistas por sus productos de tilt-up, SureBuilt est\u00e1 a\u00f1adiendo servicios de ingenier\u00eda para soporte de aplicaci\u00f3n de proyectos. Tom Fahey, <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/2018\/10\/29\/surebuilt-anade-servicios-de-ingenieria-de-tilt-up\/\" title=\"SUREBUILT A\u00d1ADE SERVICIOS DE INGENIER\u00cdA DE TILT-UP\"> Read more&#8230;<\/a><\/div>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-9698","post","type-post","status-publish","format-standard","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/9698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/comments?post=9698"}],"version-history":[{"count":2,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/9698\/revisions"}],"predecessor-version":[{"id":9702,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/9698\/revisions\/9702"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/media?parent=9698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/categories?post=9698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/tags?post=9698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}