{"id":16998,"date":"2023-06-13T16:16:55","date_gmt":"2023-06-13T21:16:55","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=16998"},"modified":"2025-06-17T13:18:25","modified_gmt":"2025-06-17T18:18:25","slug":"mas-influyente-de-2023","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/2023\/06\/13\/mas-influyente-de-2023\/","title":{"rendered":"M\u00e1s influyente de 2023"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/2023\/06\/13\/2023-most-influential-professionals\/\"><strong>English<\/strong><\/a> | Translation Provided by the TCA<\/p>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La TCA ha desarrollado un marco de trabajo para identificar a aquellos en nuestra industria que han invertido para convertirse en personas conocedoras, calificadas y reconocidas por su experiencia. Esta lista reafirma la experiencia de los profesionales de la industria que se dedican a llevar esta industria hacia el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos profesionales presentados en esta lista representan una inversi\u00f3n extraordinaria en cultivar y difundir el conocimiento y la experiencia\u201d, dijo Mitch Bloomquist, Director Ejecutivo de la Tilt-Up Concrete Association. \u201cSomos afortunados en tener una pasi\u00f3n y generosidad tan aut\u00e9nticas en los niveles m\u00e1s altos de nuestra industria\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas acumulan puntos en cinco categor\u00edas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Liderazgo: Las personas reciben diferentes puntos en esta categor\u00eda por servir en comit\u00e9s espec\u00edficos de la TCA y grupos de trabajo.<\/li><li>Credenciales: Esta categor\u00eda otorga puntos a personas por su certificaci\u00f3n y licencias profesionales.<\/li><li>Participaci\u00f3n: Mantenerse al tanto con las mejores pr\u00e1cticas y aprender de los colegas en la industria a trav\u00e9s de una asistencia consistente a eventos de la TCA aumenta en gran medida la base de conocimientos de cualquier profesional de la industria. En esta categor\u00eda se otorgan puntos por dicha participaci\u00f3n.<\/li><li>Autoridad: Aquellos destacados con premios profesionales de la TCA, conferencistas en eventos, y aquellos que escriben art\u00edculos o libros sobre la construcci\u00f3n de tilt-up reciben puntos en la categor\u00eda de autoridad.<\/li><li>Perfil: Datos exactos y personales actualizados, incluida informaci\u00f3n de contacto, nombres en redes sociales, credenciales profesionales, y m\u00e1s son datos esenciales para identificar a las personas influyentes. Los puntos en esta categor\u00eda se otorgan con base en lo completo que est\u00e9 el perfil de miembro que tiene una persona.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSeis miembros de la colaborativa de j\u00f3venes profesionales de la TCA, TILT, est\u00e1n entre los 50 principales influyentes\u201d, dijo Karen Hand, Presidenta del Consejo Administrativo de la Tilt-Up Concrete Association. \u201c\u00a1Qu\u00e9 asombroso nivel de participaci\u00f3n de los l\u00edderes de la pr\u00f3xima generaci\u00f3n! Este compromiso asegura que la TCA continuar\u00e1 avanzando la industria por muchos a\u00f1os m\u00e1s. Me emociona el futuro de nuestra organizaci\u00f3n al saber que el liderazgo del futuro est\u00e1 involucrado de esta manera.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo puedo pensar en algo m\u00e1s indicativo de la sustentabilidad de esta organizaci\u00f3n que ver a su pr\u00f3xima generaci\u00f3n usando sus voces y dejando su huella\u201d, dijo Bloomquist. \u201cEl hecho de que esta asociaci\u00f3n sea su medio predilecto proviene de una inversi\u00f3n muy intencional por parte del liderazgo en los \u00faltimos cinco a\u00f1os\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las calificaciones de la persona influyente de la industria de tilt-up se actualizan de manera din\u00e1mica en tiempo real y se presentan en dos agrupaciones: los 20 principales y los 50 principales. Uno puede excluirse voluntariamente de estas calificaciones en cualquier momento a trav\u00e9s del portal de miembros que se accede a trav\u00e9s de tilt-up.org.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-p31-D.jpg\" alt=\"\" class=\"wp-image-16992\" width=\"680\" height=\"419\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-p31-E.jpg\" alt=\"\" class=\"wp-image-16993\" width=\"680\" height=\"540\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-p31-E.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-p31-E-300x238.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-p31-E-768x610.jpg 768w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La membres\u00eda en la Tilt-Up Concrete Association es un prerrequisito para la inclusi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">English | Translation Provided by the TCA La TCA ha desarrollado un marco de trabajo para identificar a aquellos en nuestra industria que han invertido para convertirse en personas conocedoras, calificadas y reconocidas por su <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/2023\/06\/13\/mas-influyente-de-2023\/\" title=\"M\u00e1s influyente de 2023\"> Read more&#8230;<\/a><\/div>\n","protected":false},"author":6,"featured_media":16993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-16998","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/16998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/comments?post=16998"}],"version-history":[{"count":3,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/16998\/revisions"}],"predecessor-version":[{"id":17065,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/16998\/revisions\/17065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/media\/16993"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/media?parent=16998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/categories?post=16998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/tags?post=16998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}