{"id":16575,"date":"2022-08-12T11:01:50","date_gmt":"2022-08-12T16:01:50","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=16575"},"modified":"2025-06-17T12:55:45","modified_gmt":"2025-06-17T17:55:45","slug":"como-alcanzar-una-energia-de-cero-emisiones-netas-con-muros-tilt","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/2022\/08\/12\/como-alcanzar-una-energia-de-cero-emisiones-netas-con-muros-tilt\/","title":{"rendered":"C\u00d3MO ALCANZAR UNA ENERG\u00cdA DE CERO EMISIONES NETAS CON MUROS TILT"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/2022\/08\/12\/achieving-net-zero-energy-with-tilt-wall\/\"><strong>English<\/strong><\/a> | Translation Sponsored by <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Nox-Crete Products Group<\/a><\/p>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/355-Wilkinson-5848-f-1024x776-1.jpg\" alt=\"\" class=\"wp-image-16564\" width=\"680\" height=\"515\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/355-Wilkinson-5848-f-1024x776-1.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/355-Wilkinson-5848-f-1024x776-1-300x227.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/355-Wilkinson-5848-f-1024x776-1-768x582.jpg 768w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por <strong>Jesse Hunt<\/strong>, CPHC, LEED AP BD+C, WELL AP<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><meta charset=\"utf-8\"><br>Propietario: <strong>East Port Properties &#8211; Judy Wall, Presidenta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El edificio de almacenes de varios arrendatarios que mide 60,000-ft2 en Wilkinson Avenue ubicado en Dartmouth, Nova Scotia, es parte del proyecto piloto de edificios con cero emisiones de carbono del Consejo de Construcci\u00f3n Ecol\u00f3gica de Canad\u00e1 (Canada Green Building Council). El edificio combina el consumo eficiente de energ\u00eda y la generaci\u00f3n de energ\u00eda renovable para alcanzar una energ\u00eda de cero emisiones netas. En otras palabras, anualmente, el edificio genera la misma cantidad de energ\u00eda que consume. Debido a esto, el proyecto reducir\u00e1 diligentemente su contabilidad de carbono total con el paso del tiempo, al reducir continuamente su huella de carbono general. El costo de este noble logro fue mucho menor a lo que piensa la mayor\u00eda de la gente, lo cual es algo bueno ya que la propuesta de hacer m\u00e1s que solo lo m\u00ednimo para combatir el cambio clim\u00e1tico se est\u00e1 considerando de manera m\u00e1s generalizada y profunda como nunca antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los c\u00f3digos de energ\u00eda establecen la normal legal m\u00ednima con los cuales se permite construir. No alcanzaremos los objetivos clim\u00e1ticos cr\u00edticos para nuestra sociedad si no logramos superarlos y a un ritmo acelerado. Muchas organizaciones est\u00e1n tomando esto muy en serio y est\u00e1n priorizando la inversi\u00f3n en pr\u00e1cticas ambientales responsables. Para los propietarios y arrendatarios, los beneficios de invertir en un dise\u00f1o con cero emisiones est\u00e1n superando los costos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos cambiado desde aquella \u00e9poca en que las decisiones de los consumidores peque\u00f1os de usar pajillas compostables pod\u00eda considerarse como una respuesta adecuada para abordar las inquietudes por el clima. Hay mucho m\u00e1s en juego y el mercado est\u00e1 respondiendo. Como resultado de la pandemia ahora hay una presi\u00f3n sin precedentes sobre los negocios de todas las industrias para que incluyan la sustentabilidad como una caracter\u00edstica y no solo como algo sin importancia. Afortunadamente, las m\u00e9tricas y las herramientas de comunicaci\u00f3n disponibles actualmente para medir un rendimiento sustentable tambi\u00e9n han mejorado en gran medida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro entendimiento y la regulaci\u00f3n del impacto ambiental se pueden comparar con nuestro entendimiento y regulaci\u00f3n de la salud nutricional. Los or\u00edgenes y la evoluci\u00f3n de las etiquetas de datos nutricionales se remontan hasta hace m\u00e1s de un siglo cuando la Ley de Pureza de Alimentos y Medicamentos de 1906 promulg\u00f3 una ley de \u201cla verdad en las etiquetas\u201d que pretendi\u00f3 prohibir productos adulterados o mal etiquetados y elevar los est\u00e1ndares en las industrias de alimentos y medicamentos. El panel de Datos nutricionales, que comenz\u00f3 a aparecer por primera vez en los envases de alimentos en 1994, es uno de los gr\u00e1ficos m\u00e1s ampliamente reconocidos en el mundo seg\u00fan la Administraci\u00f3n de Drogas y Alimentos de EE.UU.<sup>1<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los reportes de ESG se refieren a la divulgaci\u00f3n de datos acerca de las operaciones de una organizaci\u00f3n en las categor\u00edas de medio ambiente, social y gobernabilidad. B\u00e1sicamente es un panel de datos nutricionales que utilizan los inversionistas y los consumidores que consideran el desempe\u00f1o y la pr\u00e1ctica de una compa\u00f1\u00eda en estas \u00e1reas cuando toman decisiones. La prevalencia de ESG ha acelerado desde que comenz\u00f3 la pandemia de COVID-19 y est\u00e1 cambiando r\u00e1pidamente a los mercados; el an\u00e1lisis de cr\u00e9dito en el sector de construcci\u00f3n comercial ahora tiene un componente ambiental como nunca antes. Un an\u00e1lisis reciente de Bloomberg proyect\u00f3 que los activos de ESG de 2025 bajo gesti\u00f3n (AUM) llegar\u00edan de manera conservadora a los $53 billones, un tercio del valor de todos los activos mundiales.&nbsp; Ahora, incluso el sector de almacenes est\u00e1 sintiendo la presi\u00f3n para cumplir con esto y las certificaciones de construcci\u00f3n est\u00e1n proporcionando ese servicio.<sup>2<\/sup>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay un flujo aparentemente interminable de nuevas certificaciones de \u201cconstrucci\u00f3n ecol\u00f3gica\u201d que llegan para competir en el mercado a\u00f1o tras a\u00f1o. Sin embargo, pocos est\u00e1n realmente presionando al mercado para ir m\u00e1s all\u00e1 del c\u00f3digo. Por ejemplo, LEED, es el sistema de clasificaci\u00f3n de construcci\u00f3n ecol\u00f3gica que se utiliza m\u00e1s ampliamente y puede recibir el reconocimiento por ser de los primeros en el movimiento de la construcci\u00f3n ecol\u00f3gica en los Estados Unidos. No obstante, LEED a\u00fan permite que proyectos utilicen c\u00f3digos de energ\u00eda de 2010 como base para su rendimiento de energ\u00eda; esto gana puntos en proyectos que simplemente se construyen siguiendo el c\u00f3digo. Podemos hacerlo mejor y ahora el mercado lo est\u00e1 exigiendo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si usted es una compa\u00f1\u00eda que es propietaria, desarrolla, dise\u00f1a o construye estructuras de almacenes y est\u00e1 preocupado por mejorar sus reportes de ESG, hay una manera a\u00fan no descubierta que est\u00e1 a su alcance. Muchas de estas estructuras consumen cantidades relativamente peque\u00f1as de energ\u00eda que pueden compensarse de manera eficaz y econ\u00f3mica mediante un buen dise\u00f1o, sistemas de construcci\u00f3n de calidad y atenci\u00f3n a los detalles de la construcci\u00f3n. Para lograr cero emisiones netas, el enfoque est\u00e1 primero en la eficiencia. Las cualidades aislantes y la hermeticidad se abordan en la mayor medida posible. Luego los sistemas se dimensionan con cuidado y la energ\u00eda renovable en el sitio compensa las cargas minimizadas asociadas con las operaciones de la construcci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una gran soluci\u00f3n con costos optimizados para reducir las cargas en un edificio antes de adquirir recursos renovables es el est\u00e1ndar Phius. Este es un est\u00e1ndar con eficiencia de energ\u00eda, verificado por terceros y espec\u00edfico al clima que resulta en edificios duraderos, con humedad controlada y herm\u00e9ticos. A trav\u00e9s de medidas pasivas primero las demandas de energ\u00eda se reducen, por lo que se necesitan equipos de HVAC m\u00e1s peque\u00f1os. Estos espacios incluyen ventilaci\u00f3n de recuperaci\u00f3n de calor o energ\u00eda y una calidad de aire y comodidad inigualables. Los edificios comerciales m\u00e1s grandes tienden a alcanzar el est\u00e1ndar con mayor facilidad debido a una relaci\u00f3n menor del \u00e1rea superficial a volumen. Y los almacenes de distribuci\u00f3n son especialmente buenos candidatos ya que este tipo de producto tiene bajas demandas de electricidad por pie cuadrado y adornos con una geometr\u00eda simple. El costo promedio para construir seg\u00fan este est\u00e1ndar es de 3 a 5 % de costos directos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existe mucha sinergia entre los objetivos de energ\u00eda profunda y ESG. A los arrendatarios en estos edificios se les reducir\u00e1 el gasto variable m\u00e1s grande (factura de electricidad) y pueden llegar al mercado y reportar a las partes interesadas que est\u00e1n ubicados en un edificio de alto rendimiento. Es realmente una ventaja tanto para el propietario como para el arrendatario.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/Warehouse-exterior-b.jpg\" alt=\"\" class=\"wp-image-16566\" width=\"680\" height=\"382\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/Warehouse-exterior-b.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/Warehouse-exterior-b-300x169.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/Warehouse-exterior-b-768x432.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/Warehouse-exterior-b-640x360.jpg 640w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/solarpanels-b.jpg\" alt=\"\" class=\"wp-image-16569\" width=\"680\" height=\"382\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/solarpanels-b.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/solarpanels-b-300x169.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/solarpanels-b-768x432.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/solarpanels-b-640x360.jpg 640w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ESTUDIO DE CASO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El edificio en Wilkinson Avenue, con dise\u00f1o de Powers Brown Architecture, incluye un cerramiento de edificio con muros tilt bien aislados, ventilaci\u00f3n para recuperaci\u00f3n de calor y un sistema de calefacci\u00f3n central por suelo suministrado por bombas de calor de aire a agua con una caldera de gas natural de carga m\u00e1xima. Un sistema solar fotovoltaico de medici\u00f3n neta se ha dimensionado para compensar el costo de las dos fuentes de combustible a fin de proporcionar al arrendatario cero (o casi cero) en costos de calefacci\u00f3n por el uso de un edificio t\u00edpico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La metodolog\u00eda de construcci\u00f3n de muros tilt logra tener un aislamiento continuo f\u00e1cilmente al evitar puentes t\u00e9rmicos y proporcionar un cerramiento incre\u00edblemente herm\u00e9tico ideal para controlar la energ\u00eda. Desde el punto de vista arquitect\u00f3nico, adornar el aislamiento continuo para aplicaciones de muros tilt es extremadamente sencillo. Con un cerramiento eficiente y eficaz para obtener una energ\u00eda de cero emisiones netas solo es necesario incorporar algunos elementos adicionales.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Luz diurna natural:<\/strong> Las ventanas de techos altos con tragaluces y claristorios recolectan la luz diurna y disminuyen las cargas de electricidad<\/li><li><strong>Energ\u00eda renovable: <\/strong>El sistema de paneles fotovoltaicos dimensionados para compensar el costo de una fuente de combustible resulta en costos de calefacci\u00f3n de cero emisiones netas para un consumo t\u00edpico de los arrendatarios (1.6 ekwh\/ft2).<\/li><li><strong>Eficiencia de energ\u00eda:<\/strong> Sistema mec\u00e1nico eficiente. Ventilaci\u00f3n para la recuperaci\u00f3n del calor combinada con una calefacci\u00f3n en el suelo suministrado por bombas de aire a agua. Los controles integrados basados en Internet permiten una optimizaci\u00f3n en tiempo real de todos los sistemas del edificio. Cargas m\u00e1ximas complementadas por la caldera de gas natural. Instalaciones de luz de LED para techos altos.<\/li><li><strong>Control de clima: <\/strong>Barrera t\u00e9rmica continua con una conexi\u00f3n R-40 del techo a los muros. Panel de muro tilt aislado con aislante r\u00edgido R-20. Puerta enrollable aislada con sello continuo para andenes. Niveladores de andenes con sellos para evitar la p\u00e9rdida de energ\u00eda.<\/li><li><strong>Calefacci\u00f3n por radiantes: <\/strong>Sistema de calefacci\u00f3n por radiantes en la losa con aislamiento debajo de la losa que genera mayor comodidad y menores costos de calefacci\u00f3n.<\/li><li><strong>Materiales reciclados:<\/strong> La construcci\u00f3n de acero y concreto resulta en una menor energ\u00eda incorporada a trav\u00e9s del uso de materiales reciclados y abastecimiento regional.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/warehouse-interior-b.jpg\" alt=\"\" class=\"wp-image-16571\" width=\"680\" height=\"382\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/warehouse-interior-b.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/warehouse-interior-b-300x169.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/warehouse-interior-b-768x432.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/08\/warehouse-interior-b-640x360.jpg 640w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ACERCA DE POWERS BROWN ARCHITECTURE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Powers Brown Architecture siempre ha apoyado el concepto de \u201csustentabilidad\u201d en el dise\u00f1o. El proceso del razonamiento es que la \u201cconstrucci\u00f3n ecol\u00f3gica\u201d es una extensi\u00f3n de un buen dise\u00f1o econ\u00f3mico. Si se comienza con un buen dise\u00f1o econ\u00f3mico, estar\u00e1 en el camino correcto para ofrecer un producto que ahora cuenta con la etiqueta de \u201cecol\u00f3gico\u201d en su producto final. Esta es una pr\u00e1ctica que los directores han estado implementando durante m\u00e1s de treinta a\u00f1os. Actualmente, con m\u00e1s y m\u00e1s problemas ambientales en primer plano, Powers Brown Architecture est\u00e1 a la vanguardia. La empresa incorpora productos saludables y ambientalmente responsables que cumplen con la definici\u00f3n \u201cecol\u00f3gica\u201d en los proyectos cuando lo permite el programa y el presupuesto. Powers Brown Architecture tiene un grupo de sustentabilidad interno dirigido por Jeanette Shaw, AIA, RID, LEED AP, y Jesse Hunt, CPHC, LEED AP BD+C, WELL AP, que se concentra en orientar a los proyectos en cualesquiera que puedan ser sus objetivos de sustentabilidad. Adem\u00e1s, Powers Brown Architecture tiene 12 gerentes de proyecto, arquitectos de proyecto, dise\u00f1adores de interiores y dise\u00f1adores de proyecto profesionales acreditados por LEED.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">English | Translation Sponsored by Nox-Crete Products Group Por Jesse Hunt, CPHC, LEED AP BD+C, WELL AP Propietario: East Port Properties &#8211; Judy Wall, Presidenta El edificio de almacenes de varios arrendatarios que mide 60,000-ft2 <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/2022\/08\/12\/como-alcanzar-una-energia-de-cero-emisiones-netas-con-muros-tilt\/\" title=\"C\u00d3MO ALCANZAR UNA ENERG\u00cdA DE CERO EMISIONES NETAS CON MUROS TILT\"> Read more&#8230;<\/a><\/div>\n","protected":false},"author":6,"featured_media":16564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-16575","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/16575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/comments?post=16575"}],"version-history":[{"count":7,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/16575\/revisions"}],"predecessor-version":[{"id":16636,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/16575\/revisions\/16636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/media\/16564"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/media?parent=16575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/categories?post=16575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/tags?post=16575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}