{"id":15119,"date":"2020-12-23T09:30:48","date_gmt":"2020-12-23T14:30:48","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=15119"},"modified":"2025-06-12T14:39:11","modified_gmt":"2025-06-12T19:39:11","slug":"tilt-realizara-un-dia-de-trabajo-el-13-de-enero-de-2021","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/2020\/12\/23\/tilt-realizara-un-dia-de-trabajo-el-13-de-enero-de-2021\/","title":{"rendered":"TILT REALIZAR\u00c1 UN D\u00cdA DE TRABAJO EL 13 DE ENERO DE 2021"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/2020\/12\/23\/tilt-to-hold-work-day-on-january-13-2021\/\"><strong>English<\/strong><\/a> | Translation Sponsored by <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Nox-Crete Products Group<\/a><\/p>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Como un miembro de la asociaci\u00f3n, usted es animado a nominar a aquellos l\u00edderes de gran potencial en su organizaci\u00f3n para que participen en un pr\u00f3ximo evento de incorporaci\u00f3n y trabajo organizado por TILT. El evento virtual, planificado para el 13 de enero de 2021, tiene como objetivo conectar mejor a los profesionales j\u00f3venes interesados en involucrarse con el grupo en un ambiente donde pueden r\u00e1pidamente ser orientados y empezar a trabajar.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"280\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Work-Day-r.jpg\" alt=\"\" class=\"wp-image-15116\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Work-Day-r.jpg 680w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Work-Day-r-300x124.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la fundaci\u00f3n de los grupos solo dos a\u00f1os atr\u00e1s, han tenido un impacto tremendo en la programaci\u00f3n de la asociaci\u00f3n y, de hecho, han aconsejado a la junta de directores en asuntos estructurales importantes. Las iniciativas actuales incluyen la formaci\u00f3n de un programa de tutor\u00eda, estudio detallado de tilt-up, restructuraci\u00f3n de la l\u00ednea t\u00e9cnica directa, programaci\u00f3n de medios sociales y m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento de d\u00eda de trabajo del 13 de enero abrir\u00e1 con un panel de discusi\u00f3n dirigido por el grupo de liderazgo de TILT seguido por introducciones cortas a las varias Categor\u00edas de Participaci\u00f3n (COE, por sus siglas en ingl\u00e9s) que estructuran las iniciativas del grupo. Se invitar\u00e1n a los nuevos miembros de TILT a seleccionar iniciativas que se alinean con sus destrezas e intereses y que empiecen a trabajar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por medio de su formaci\u00f3n y desarrollo, TILT prosper\u00f3 por sus reuniones en persona y la importancia de la interacci\u00f3n cara a cara se consider\u00f3 una herramienta absolutamente esencial para su \u00e9xito. A tal punto que la TCA invirti\u00f3 decenas de miles de d\u00f3lares, en los \u00faltimos dos a\u00f1os, en eventos en persona y actividades para el grupo. La pandemia de COVID-19 ha interrumpido la habilidad del grupo de reunirse en persona por lo que, por el momento, un evento virtual tendr\u00e1 que ser suficiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los l\u00edderes de TILT acordaron que tener un d\u00eda dedicado en su calendario (virtual o en persona) para un esfuerzo y producci\u00f3n enfocados relacionados con este trabajo es m\u00e1s f\u00e1cil de planificar. A\u00fan m\u00e1s, sintieron que sus empleadores estaban en una mejor posici\u00f3n para apoyar los proyectos de voluntariado concentrado que este tiempo espor\u00e1dico lejos del trabajo. El esfuerzo es tambi\u00e9n m\u00e1s eficiente de esta manera porque miembros no est\u00e1n realizando reuniones de las COE de 30 minutos entre tareas relacionadas con el trabajo de m\u00e1s prioridad donde su atenci\u00f3n est\u00e1 inevitablemente dividida. De igual importancia, esta estrategia permite a los miembros de TILT la habilidad de evitar que una buena parte de su trabajo voluntario se filtre en el tiempo con sus familias, amigos e intereses no relacionados con el trabajo o tilt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Busque m\u00e1s informaci\u00f3n y detalles de registro en tilt-up.org\/events.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre TILT<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2018, la Junta de Directores de la Tilt-Up Concrete Association formaliz\u00f3 una iniciativa para establecer una colaboraci\u00f3n de profesionales j\u00f3venes con acceso a los recursos interdisciplinarios de la TCA para convertirse en los l\u00edderes futuros de la organizaci\u00f3n, al autoiniciar programas que manifiestan los problemas de hoy resueltos en t\u00e9rminos del futuro. Un total de 39 personas fueron seleccionadas para participar en un evento de inicio en Las Vegas el 22 de enero de 2019 durante World of Concrete. En este evento, se les pidi\u00f3 a los participantes que formularan su misi\u00f3n, programaci\u00f3n y estructura por medio de una serie de ejercicios dise\u00f1ados por un facilitador profesional, programada con los objetivos y pol\u00edticas descritos por la Junta de Directores de la TCA.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">English | Translation Sponsored by Nox-Crete Products Group Como un miembro de la asociaci\u00f3n, usted es animado a nominar a aquellos l\u00edderes de gran potencial en su organizaci\u00f3n para que participen en un pr\u00f3ximo evento <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/2020\/12\/23\/tilt-realizara-un-dia-de-trabajo-el-13-de-enero-de-2021\/\" title=\"TILT REALIZAR\u00c1 UN D\u00cdA DE TRABAJO EL 13 DE ENERO DE 2021\"> Read more&#8230;<\/a><\/div>\n","protected":false},"author":6,"featured_media":15116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-15119","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/15119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/comments?post=15119"}],"version-history":[{"count":2,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/15119\/revisions"}],"predecessor-version":[{"id":15311,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/posts\/15119\/revisions\/15311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/media\/15116"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/media?parent=15119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/categories?post=15119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/wp-json\/wp\/v2\/tags?post=15119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}