{"id":9671,"date":"2018-10-29T10:55:10","date_gmt":"2018-10-29T15:55:10","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=9671"},"modified":"2025-06-02T11:29:56","modified_gmt":"2025-06-02T16:29:56","slug":"thompson-ten-logistics-center-llega-a-baytown-texas","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2018\/10\/29\/thompson-ten-logistics-center-llega-a-baytown-texas\/","title":{"rendered":"THOMPSON TEN LOGISTICS CENTER LLEGA A BAYTOWN, TEXAS"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/2018\/10\/29\/thompson-ten-logistics-center-coming-to-baytown-texas\/\"><strong>Ingl\u00e9s<\/strong><\/a> | Traducci\u00f3n patrocinada por <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de productos Nox-Crete<\/a><\/p>\n<\/div>\n<p><strong><br \/>\nInversiones y Desarrollo Ventures (IDV)<\/strong>, colabora con Powers Brown Architecture y Slate Construction para iniciar la construcci\u00f3n de un parque industrial de m\u00e1s de 360 000 pies cuadrados. El Thompson Ten Logistics Center traer\u00e1 dos estructuras de hormig\u00f3n prefabricado a Baytown, Texas. Este parque industrial planificado de m\u00e1s de 28 acres tendr\u00e1 entrada y salida inmediata a la autopista interestatal 10 y acceso directo a las terminales de Barbour\u2019s Cut y Baytown Container. El edificio 1 constar\u00e1 de 130,000 pies cuadrados de configuraci\u00f3n de carga frontal, que incluir\u00e1 (31) puertas de carga de 9\u00d710 y (2) puertas levadizas de 12\u00d714. Ser\u00e1 posible el almacenamiento de materiales peligrosos. El edificio 2 tendr\u00e1 260,000 pies cuadrados de configuraci\u00f3n de transferencia directa, que constar\u00e1 de (61) puertas de carga de 9\u00d710 y (4) puertas levadizas de 12\u00d714. Ambos edificios tendr\u00e1n m\u00e1s de 80 posiciones de almacenamiento de camiones y m\u00e1s de 190 espacios de estacionamiento con l\u00edneas. Tambi\u00e9n habr\u00e1 espacios para oficinas en ambos edificios.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Investment and Development Ventures (IDV), colabora con Powers Brown Architecture y Slate Construction para emprender la construcci\u00f3n de un parque industrial de m\u00e1s de 360,000 pies cuadrados. <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2018\/10\/29\/thompson-ten-logistics-center-llega-a-baytown-texas\/\" title=\"THOMPSON TEN LOGISTICS CENTER LLEGA A BAYTOWN, TEXAS\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-9671","post","type-post","status-publish","format-standard","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/9671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=9671"}],"version-history":[{"count":3,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/9671\/revisions"}],"predecessor-version":[{"id":9674,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/9671\/revisions\/9674"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=9671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=9671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=9671"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}