{"id":9406,"date":"2018-04-20T12:21:16","date_gmt":"2018-04-20T17:21:16","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=9406"},"modified":"2025-06-02T10:34:13","modified_gmt":"2025-06-02T15:34:13","slug":"ayuda-para-desarrollar-la-proxima-generacion-de-trabajadores-calificados","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2018\/04\/20\/ayuda-para-desarrollar-la-proxima-generacion-de-trabajadores-calificados\/","title":{"rendered":"Ayuda para desarrollar la pr\u00f3xima generaci\u00f3n de trabajadores calificados"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/2018\/04\/20\/building-the-next-generation-of-skilled-labors\/\"><strong>Ingl\u00e9s<\/strong><\/a> | Traducci\u00f3n patrocinada por <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de productos Nox-Crete<\/a><\/p>\n<\/div>\n<p>La construcci\u00f3n es una de las industrias m\u00e1s grandes del pa\u00eds, con m\u00e1s de 7 millones de empleos asalariados y 1.9 millones de trabajadores por cuenta propia. Durante la d\u00e9cada pasada, la industria de la construcci\u00f3n se vio afectada por una creciente escasez de mano de obra calificada. Debido a esta escasez, Martin Concrete ha intentado buscar una soluci\u00f3n no convencional. Uno de los enfoques \u00fanicos de Martin sobre este tema fue asociarse con escuelas secundarias locales que tienen academias y\/o programas de construcci\u00f3n para hablar sobre los beneficios de ingresar a este campo. <\/p>\n<p>\u201cMartin Concrete ha intentado crear un programa para ayudar a reparar la brecha y permitir que la pr\u00f3xima generaci\u00f3n considere a la construcci\u00f3n como una carrera profesional. Al hacer presentaciones en clase y recibir visitas en el sitio, esperamos ofrecer un mensaje optimista e impactante a la pr\u00f3xima generaci\u00f3n\u201d. \u2014 Kristin McKenzie<\/p>\n<p>Una escuela secundaria en particular con la que Martin ha trabajado estrechamente es la escuela secundaria Berkmar High School, en Lilburn, Georgia. Berkmar es una de las pocas escuelas secundarias del sureste que ofrece un programa acad\u00e9mico de construcci\u00f3n. La academia ofrece a los estudiantes de secundaria la posibilidad de aprender con un plan de estudios tradicional, pero que al mismo tiempo se relaciona con los elementos de la fuerza laboral de la vida real. Por ejemplo, las matem\u00e1ticas se pueden ense\u00f1ar en relaci\u00f3n con las medidas en un plano, o el ingl\u00e9s se puede explicar a trav\u00e9s del lenguaje de un contratista. Este enfoque acad\u00e9mico \u00fanico permite a los estudiantes obtener conocimientos y experiencia simult\u00e1neamente, y deber\u00eda darles una ventaja cuando ingresen a la fuerza laboral calificada. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2018\/04\/Ready-Mix-Plant--1024x804.jpg\" alt=\"\" width=\"664\" height=\"534\" class=\"aligncenter size-large wp-image-9395\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2018\/04\/171111157-2-1024x684.jpg\" alt=\"\" width=\"664\" height=\"544\" class=\"aligncenter size-large wp-image-9398\" \/><\/p>\n<p>Durante los meses de mayo y noviembre de 2017, Martin Concrete organiz\u00f3 dos visitas guiadas a las obras para los estudiantes en el marco del proyecto del Centro de Distribuci\u00f3n de UPS de Martin Concrete. Este proyecto abarca 2,74 millones de pies cuadrados de hormig\u00f3n (aproximadamente 85 000 yardas c\u00fabicas). La magnitud del proyecto permiti\u00f3 organizar visitas de estudiantes en casi cualquier \u00e9poca del a\u00f1o. Durante estas visitas, los equipos explicaron las ventajas y las diferencias entre incorporarse a la fuerza laboral calificada inmediatamente despu\u00e9s de graduarse de la escuela secundaria o elegir asistir primero a la universidad. Grupos de 30 estudiantes recorrieron el proyecto a lo largo de diferentes fases de la construcci\u00f3n. Un grupo observ\u00f3 a un equipo de carpinteros que preparaban y colocaban una losa de concreto en una pendiente, mientras un equipo de tilt preparaba algunos de los 540 paneles tilt. Otro grupo de estudiantes tuvo la oportunidad de aprender y ver c\u00f3mo se colocaban 30,000 pies cuadrados de pavimento de concreto que los acabadores internos de Martin estaban instalando. Luego hicieron un recorrido por la planta port\u00e1til de concreto de Martin y pudieron ver c\u00f3mo se fabrica la mezcla de concreto, lista para usar. Al realizar estas visitas, Martin Concrete permiti\u00f3 a los estudiantes ver de primera mano los procesos de los trabajadores principales, lo que gener\u00f3 una nueva participaci\u00f3n e inter\u00e9s que de otra manera podr\u00eda no existir. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2018\/04\/Paving-Pour--1024x786.jpg\" alt=\"\" width=\"664\" height=\"522\" class=\"aligncenter size-large wp-image-9400\" \/><\/p>\n<p>Donyale Miller, profesora de arquitectura en la secundaria Berkmar, pudo experimentar las visitas guiadas con otros profesores. Ella confirm\u00f3 que el programa que proporciona Martin Concrete ayuda a sus estudiantes con los an\u00e1lisis en clase y tambi\u00e9n not\u00f3 que los estudiantes se interesan m\u00e1s por un futuro en la construcci\u00f3n. Los estudiantes comenzaron a preguntar acerca de la edad que se debe tener para comenzar una carrera en la construcci\u00f3n, cu\u00e1nto tiempo les toma avanzar en la industria y la cantidad de horas que se requiere. La se\u00f1ora Miller afirm\u00f3: <\/p>\n<p>\u201cEl estudiante pudo ver de primera mano c\u00f3mo funcionan las cosas. En la clase de arquitectura podemos ver c\u00f3mo se combinan las cosas que dibujamos. En realidad, no sab\u00edan lo agradable y rentable que podr\u00eda ser la profesi\u00f3n. No se daban cuenta de la necesidad ni de qu\u00e9 tan r\u00e1pido pueden avanzar profesionalmente. <\/p>\n<p>Robert Rodgers, el maestro de construcci\u00f3n de Berkmar, sinti\u00f3 que las visitas permit\u00edan a los maestros crear planes de lecci\u00f3n realistas para las clases. \u201cPudimos tomar lo que vimos e implementarlo en el aula creando modelos a escala para ayudar a imitar los procesos reales\u201d, dijo Rodgers al ser consultado sobre c\u00f3mo se reflejan las demostraciones de campo en el aula. <\/p>\n<p>\u201cCreo que Martin Concrete realmente se preocupa por los j\u00f3venes de nuestra comunidad, me gusta la forma en que est\u00e1n ampliando sus oportunidades para atraer a los estudiantes de nuestra escuela. \u00a1Hacen que mi trabajo sea m\u00e1s interesante y me ayudan a llevar experiencias de la vida real a mi clase!\u201d \u2014 Robert Rodgers<\/p>\n<p>John Tonolone, el entrenador de Berkmar, est\u00e1 impresionado con el enfoque creativo de Martin Concrete ante esta escasez de mano de obra. <\/p>\n<p>\u201cMartin Concrete es el modelo que buscan las escuelas en un aliado de la industria. Desde la primera conversaci\u00f3n, mostraron inter\u00e9s en los estudiantes de Berkmar y entendieron que el tiempo y la colaboraci\u00f3n eran m\u00e1s efectivos que el apoyo monetario que los colaboradores comerciales usualmente ofrecen a las escuelas. Kristin y su personal se tomaron el tiempo para hablar con el profesorado de Berkmar sobre lo que estaban ense\u00f1ando en clase para que juntos pudieran descubrir qu\u00e9 recursos y personas de Martin Concrete encajaban mejor con el plan de estudios. Reforzaron esto hablando con los estudiantes en el sitio y en el aula sobre la industria y sobre qu\u00e9 esperar cuando visitan el sitio de UPS. Este enfoque completo de las visitas mostr\u00f3 una inquietud por nuestros estudiantes y su futuro, as\u00ed como tambi\u00e9n permiti\u00f3 a los estudiantes y al personal ver f\u00e1cilmente las conexiones entre el aula y el mundo real, y as\u00ed fortalecer su inter\u00e9s en la industria\u201d. \u2014 John Tonolone<\/p>\n<p>Debido a que Martin es un contratista de concreto integral, los estudiantes tuvieron la oportunidad de hablar y aprender sobre una variedad de puestos dentro del mundo del concreto. Estas entrevistas incluyeron gerentes de proyecto, acabadores de concreto, conductores de camiones, carpinteros, gerentes de planta de concreto, operadores de gr\u00faas, operadores de equipos y personal de seguridad. Esto demuestra que la industria tiene m\u00e1s para ofrecer de lo que se podr\u00eda aprender solo de un libro de texto. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2018\/04\/Panel-Tilt-1080-1024x678.jpg\" alt=\"\" width=\"664\" height=\"450\" class=\"aligncenter size-large wp-image-9404\" \/><\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Espa\u00f1ol (Latinoam\u00e9rica) | Traducci\u00f3n patrocinada por Nox-Crete Products Group La construcci\u00f3n es una de las industrias m\u00e1s grandes del pa\u00eds, con m\u00e1s de 7 millones de empleos asalariados y 1.9 millones de trabajadores por cuenta propia. <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2018\/04\/20\/ayuda-para-desarrollar-la-proxima-generacion-de-trabajadores-calificados\/\" title=\"Ayuda para desarrollar la pr\u00f3xima generaci\u00f3n de trabajadores calificados\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":9395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-9406","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/9406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=9406"}],"version-history":[{"count":4,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/9406\/revisions"}],"predecessor-version":[{"id":9410,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/9406\/revisions\/9410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/9395"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=9406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=9406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=9406"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}