{"id":1925,"date":"2013-01-17T16:01:13","date_gmt":"2013-01-17T21:01:13","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=1925"},"modified":"2015-06-08T02:33:24","modified_gmt":"2015-06-08T07:33:24","slug":"tilt-up-provides-speed-and-efficiency-for-a-company-on-the-move-american-tire-londonderry-nh","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2013\/01\/17\/tilt-up-provides-speed-and-efficiency-for-a-company-on-the-move-american-tire-londonderry-nh\/","title":{"rendered":"La construcci\u00f3n Tilt-Up aporta rapidez y eficiencia a una empresa en plena expansi\u00f3n: American Tire \u2013 Londonderry, Nuevo Hampshire"},"content":{"rendered":"<p><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2013\/01\/AT-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1927\" title=\"AT-1\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2013\/01\/AT-1-224x300.jpg\" alt=\"\" width=\"224\" height=\"300\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2013\/01\/AT-1-224x300.jpg 224w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2013\/01\/AT-1-225x300.jpg 225w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2013\/01\/AT-1.jpg 680w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/a>Desde 1935, American Tire Distributors ha prestado apoyo a los distribuidores de llantas, talleres de servicio y talleres de tuning de todo el pa\u00eds, garantizando una entrega r\u00e1pida y c\u00f3moda de los productos, herramientas y programas que necesitan para atender a una naci\u00f3n en constante movimiento. American Tire ofrece a sus clientes un paquete completo de llantas, rines personalizados, equipo de servicio, suministros para talleres y un conjunto completo de recursos comerciales necesarios para enfrentar el desaf\u00edo de un panorama minorista cada vez m\u00e1s exigente y competitivo. Cuando lleg\u00f3 el momento de construir su pr\u00f3xima instalaci\u00f3n de distribuci\u00f3n en Londonderry, Nuevo Hampshire, American Tire quer\u00eda el mismo servicio de calidad de parte de su contratista.<\/p>\n<p>BC Construction Group es una empresa relativamente nueva, pero cuenta entre su personal con profesionales que tienen muchos a\u00f1os de experiencia en la construcci\u00f3n con paneles prefabricados y relaciones duraderas en el sector de la construcci\u00f3n con hormig\u00f3n. Fueron precisamente estas relaciones las que unieron a American Tire, BC Group y Seretta.<\/p>\n<p>\u201cNo hemos trabajado mucho en el noreste. M\u00e1s o menos segu\u00edamos a uno de nuestros clientes, pero trabajando con <a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/members\/member_card.php\/?id=10221\" target=\"_blank\">AH Harris<\/a> \u201dEn general, sali\u00f3 bien\u00bb. David Peltier, director de proyectos, <a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/members\/member_card.php\/?id=10107\" target=\"_blank\">Seretta Construction<\/a> Mid-Atlantic, LLC.<\/p>\n<p>BC Construction Group y Seretta Construction cumplieron con los requisitos de American Tire mediante un paquete integral de dise\u00f1o y construcci\u00f3n con la t\u00e9cnica tilt-up. Las instalaciones construidas con la t\u00e9cnica tilt-up satisfac\u00edan todas las necesidades de American Tire: un calendario de construcci\u00f3n ajustado, un dise\u00f1o de paredes r\u00edgidas, sostenibilidad y flexibilidad.<\/p>\n<p>Eric Moore, director de proyectos y superintendente de BC Construction Group, sab\u00eda que la construcci\u00f3n con paneles prefabricados era la opci\u00f3n adecuada para este proyecto debido a los plazos ajustados. \u201cQuer\u00edamos optar por la construcci\u00f3n con paneles prefabricados por su rapidez y eficiencia\u201d.\u201d<\/p>\n<p>La superficie total del edificio era de 11 613 m\u00b2, con 416 m\u00b2 destinados a oficinas y el resto de las instalaciones, 11 207 m\u00b2, ocupados por un gran almac\u00e9n de gran luz con 48 puertas de carga para camiones.<\/p>\n<p>BC Construction Group y Seretta prometieron rapidez, y eso es precisamente lo que cumplieron. La excavaci\u00f3n del terreno comenz\u00f3 el 5 de junio; los cimientos se colocaron menos de 10 d\u00edas despu\u00e9s. La primera losa se hormigon\u00f3 dos semanas m\u00e1s tarde, justo antes de las vacaciones del 4 de julio. En solo unos d\u00edas se encofraron y hormigonaron 65 paneles de pared.<\/p>\n<p>El montaje de los paneles comenz\u00f3 el 8 de agosto, dos meses despu\u00e9s de la fecha de inicio del proyecto.<\/p>\n<p>El panel m\u00e1s grande med\u00eda 13,33 m de alto por 8,17 m de ancho y pesaba 55 100 kg. Para poder manejar los paneles m\u00e1s altos, de 14,60 m, y el m\u00e1s ancho, de 9,70 m, Seretta utiliz\u00f3 una gr\u00faa sobre orugas de 220 toneladas.<\/p>\n<p>Al dise\u00f1ar el sistema de elevaci\u00f3n y sujeci\u00f3n de estos paneles, fue fundamental aprovechar al m\u00e1ximo el acero estructural ya existente. Gracias al refuerzo estructural ya presente en la fachada, no fue necesario a\u00f1adir barras de refuerzo adicionales para soportar las tensiones del hormig\u00f3n. El patr\u00f3n de juntas de estos paneles inclu\u00eda juntas tanto verticales como horizontales, lo que hizo imprescindible contar con un buen sistema de sujeci\u00f3n para eliminar cualquier tensi\u00f3n horizontal. Con A.H. Harris y <a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/members\/member_card.php\/?id=10242\" target=\"_blank\">Meadow Burke<\/a>\u2019Gracias a la experiencia de [nombre de la empresa], pudimos completar este trabajo sin necesidad de a\u00f1adir barras de refuerzo, lo que mejor\u00f3 considerablemente el resultado final del proyecto.<\/p>\n<p>Era la primera vez que Meadow Burke colaboraba con la divisi\u00f3n noreste de Seretta, y quer\u00edan demostrarle a Seretta las ventajas de contar con ellos para sus edificios construidos con el m\u00e9todo tilt-up. El proyecto se desarroll\u00f3 a un ritmo acelerado; Meadow Burke complet\u00f3 el dise\u00f1o de los paneles en solo cuatro d\u00edas para garantizar que Seretta pudiera cumplir con sus plazos y mantener el proyecto seg\u00fan lo previsto. El ingeniero de Meadow Burke, Ernie Garc\u00eda, se\u00f1al\u00f3 que \u201ceste proyecto es un ejemplo perfecto de c\u00f3mo el m\u00e9todo tilt-up es una forma de construcci\u00f3n m\u00e1s eficiente, m\u00e1s econ\u00f3mica y m\u00e1s r\u00e1pida, lo que lo convierte en una situaci\u00f3n beneficiosa para todos los involucrados\u201d.\u201d<\/p>\n<p>En conjunto, el equipo proporcion\u00f3 a American Tire Distributors el paquete completo necesario para hacer frente al reto de un panorama cada vez m\u00e1s exigente y competitivo, y lo hizo de la misma manera en que American Tire abastece a sus clientes: con entregas r\u00e1pidas y convenientes, imprescindibles para dar servicio a un pa\u00eds en constante movimiento.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Desde 1935, American Tire Distributors ha prestado apoyo a los distribuidores de llantas, talleres de reparaci\u00f3n y tiendas de tuning de todo el pa\u00eds, garantizando una entrega r\u00e1pida y c\u00f3moda de los productos, herramientas y programas que necesitan para atender a los clientes de todo el pa\u00eds. <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2013\/01\/17\/tilt-up-provides-speed-and-efficiency-for-a-company-on-the-move-american-tire-londonderry-nh\/\" title=\"La construcci\u00f3n Tilt-Up aporta rapidez y eficiencia a una empresa en plena expansi\u00f3n: American Tire \u2013 Londonderry, Nuevo Hampshire\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":2,"featured_media":1926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,14],"tags":[],"class_list":["post-1925","post","type-post","status-publish","format-standard","has-post-thumbnail","category-industry","category-member_news"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=1925"}],"version-history":[{"count":12,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1925\/revisions"}],"predecessor-version":[{"id":7334,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1925\/revisions\/7334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/1926"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=1925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=1925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=1925"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}