{"id":17346,"date":"2023-11-29T12:19:20","date_gmt":"2023-11-29T17:19:20","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=17346"},"modified":"2025-10-28T10:13:46","modified_gmt":"2025-10-28T15:13:46","slug":"a-thriving-hub-of-education","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2023\/11\/29\/a-thriving-hub-of-education\/","title":{"rendered":"Un centro pr\u00f3spero de educaci\u00f3n"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"526\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-a.jpg\" alt=\"\" class=\"wp-image-17348\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-a.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-a-300x154.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-a-768x395.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La Convenci\u00f3n y Expo Tilt-Up 2023 en Tampa, Florida, ofreci\u00f3 un fuerte enfoque en la educaci\u00f3n, cumpliendo su reputaci\u00f3n como el principal encuentro de la industria global de tilt-up. Los asistentes tuvieron a su disposici\u00f3n una amplia gama de oportunidades educativas, todas dise\u00f1adas para empoderar a los profesionales de la industria con valiosas ideas y conocimientos que podr\u00edan aplicarse directamente a su trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento ofreci\u00f3 recorridos educativos especializados adaptados a diferentes intereses y niveles de experiencia. El Recorrido de Construcci\u00f3n proporcion\u00f3 a supervisores de campo y gerentes de proyecto informaci\u00f3n cr\u00edtica, incluida la oportunidad de obtener la recertificaci\u00f3n de Supervisor o T\u00e9cnico de Tilt-Up ACI\/TCA. El Recorrido de Dise\u00f1o fue curado para profesionales involucrados en el dise\u00f1o e ingenier\u00eda de proyectos de tilt-up, ofreciendo educaci\u00f3n en profundidad espec\u00edfica para sus necesidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una caracter\u00edstica destacada fue la Pista de Educaci\u00f3n en Espa\u00f1ol, un testimonio del compromiso de la industria con la inclusi\u00f3n. Este programa de dos d\u00edas y la oportunidad de certificaci\u00f3n tilt-up celebraron y apoyaron a la fuerza laboral hispana, tanto en Estados Unidos como en otros lugares. Reconoci\u00f3 la importancia de proporcionar contenido en idiomas nativos para promover el intercambio de conocimientos y el crecimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los reci\u00e9n llegados a la construcci\u00f3n tilt-up (o en voladizo\/prefabricada), Tilt-Up 101 sirvi\u00f3 como una introducci\u00f3n completa, cubriendo los principios b\u00e1sicos de dise\u00f1o, administraci\u00f3n y construcci\u00f3n. Tilt-Up Engineering 101, por otro lado, se adentr\u00f3 en los dise\u00f1os de ingenier\u00eda estructural y los m\u00e9todos de construcci\u00f3n para los paneles de muro tilt-up, beneficiando tanto a los reci\u00e9n llegados como a los profesionales experimentados en el campo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este programa educativo fue posible gracias al generoso patrocinio de l\u00edderes de la industria, con la Pista de Espa\u00f1ol patrocinada por Tilt-Up Asesores. La Pista de Construcci\u00f3n fue apoyada por Integrated Window Systems LLC y Tiger Concrete and Screed LLC, mientras que Dayton Superior Corporation y Needham DBS patrocinaron la Pista de Dise\u00f1o. White Cap proporcion\u00f3 patrocinio para Tilt-Up Construction 101 e IconX LLC apoy\u00f3 Tilt-Up Engineering 101. El patrocinador principal, Total Integrated Panel Systems, enriqueci\u00f3 las ofertas educativas del evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En resumen, la Convenci\u00f3n y Expo de Tilt-Up 2023 fue un centro de educaci\u00f3n pr\u00f3spero, gracias a la dedicaci\u00f3n de profesionales de la industria y al generoso apoyo de nuestros patrocinadores. El evento ejemplific\u00f3 el compromiso de la industria con el aprendizaje y el crecimiento continuos, preparando el escenario para un futuro m\u00e1s brillante en la construcci\u00f3n de tilt-up.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al concluir nuestro recorrido por las \u201cCr\u00f3nicas de la Convenci\u00f3n\u201d, reflexionamos sobre el inmenso conocimiento, la camarader\u00eda y la innovaci\u00f3n que definieron la Convenci\u00f3n y Expo Tilt-Up 2023 en Tampa. Esperamos que estos art\u00edculos de resumen le hayan permitido revivir los momentos clave, la valiosa educaci\u00f3n y los logros sobresalientes que hicieron de este evento algo excepcional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro sincero agradecimiento a nuestros patrocinadores principales, Leviat, Seretta Construction Inc. y White Cap, por su firme apoyo. Tambi\u00e9n extendemos nuestra gratitud a los dedicados patrocinadores locales anfitriones que desempe\u00f1aron un papel fundamental en el \u00e9xito de esta reuni\u00f3n. Si bien las cr\u00f3nicas pueden terminar, el impacto de la convenci\u00f3n contin\u00faa resonando en toda la industria tilt-up.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos con ansias el pr\u00f3ximo cap\u00edtulo de progreso, aprendizaje y conexi\u00f3n en futuras convenciones, donde continuaremos construyendo juntos una comunidad m\u00e1s fuerte e innovadora.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-b.jpg\" alt=\"\" class=\"wp-image-17349\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-b.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-b-300x150.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/11\/32-b-768x384.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">La Convenci\u00f3n y Expo Tilt-Up 2023 en Tampa, Florida, ofreci\u00f3 un fuerte enfoque en la educaci\u00f3n, haciendo honor a su reputaci\u00f3n como el principal encuentro de la industria global de tilt-up. A los asistentes se les present\u00f3 una diversa <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2023\/11\/29\/a-thriving-hub-of-education\/\" title=\"Un centro pr\u00f3spero de educaci\u00f3n\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":17351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,29],"tags":[],"class_list":["post-17346","post","type-post","status-publish","format-standard","has-post-thumbnail","category-industry","category-news"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/17346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=17346"}],"version-history":[{"count":4,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/17346\/revisions"}],"predecessor-version":[{"id":19047,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/17346\/revisions\/19047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/17351"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=17346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=17346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=17346"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}