{"id":1723,"date":"2012-08-13T16:39:57","date_gmt":"2012-08-13T21:39:57","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=1723"},"modified":"2020-01-27T14:53:40","modified_gmt":"2020-01-27T19:53:40","slug":"tilt-up-concrete-association-announces-new-speaker-to-round-out-convention-presentations","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2012\/08\/13\/tilt-up-concrete-association-announces-new-speaker-to-round-out-convention-presentations\/","title":{"rendered":"La Asociaci\u00f3n de Hormig\u00f3n Tilt-Up anuncia un nuevo ponente para completar el programa de ponencias de la convenci\u00f3n"},"content":{"rendered":"<p><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/08\/cracked-concrete.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-1724\" title=\"Concreto agrietado\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/08\/cracked-concrete-290x290.jpg\" alt=\"\" width=\"290\" height=\"290\" \/><\/a>La Tilt-Up Concrete Association (TCA) ha anunciado la incorporaci\u00f3n de Kim Basham PhD, PE, al programa de la Convenci\u00f3n TCA 2012.<\/p>\n<p>Basham, presidente de KB Engineer, LLC, presentar\u00e1 \u201c<a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/t1b\/\">Control de grietas en losas<\/a>\u201duna sesi\u00f3n enfocada en las causas de las grietas por asentamiento t\u00e9rmico en seco. Su presentaci\u00f3n, que se llevar\u00e1 a cabo el jueves 4 de octubre de 8 a 10 a. m., est\u00e1 dise\u00f1ada para educar a los asistentes sobre c\u00f3mo desarrollar una filosof\u00eda de control de grietas que sea una combinaci\u00f3n de enfoque de dise\u00f1o y efectividad de la construcci\u00f3n para minimizar las grietas aleatorias en las losas.<\/p>\n<p>Su presentaci\u00f3n forma parte de la pista de supervisores de campo, una nueva oferta de este a\u00f1o. Patrocinada por Citadel Contractors, la pista ofrece sesiones convenientes que abordan problemas cr\u00edticos para el desarrollo y el \u00e9xito de los supervisores de campo y gerentes de proyecto de hoy en d\u00eda. La pista tambi\u00e9n est\u00e1 dise\u00f1ada para cumplir con la \u00faltima actualizaci\u00f3n del programa ACI\/TCA Certified Tilt-Up Supervisor and Technician al proporcionar las UC (Unidades de Cr\u00e9ditos, CEUs en ingl\u00e9s) necesarias para la recertificaci\u00f3n. Hasta la adaptaci\u00f3n a una opci\u00f3n de UC para la recertificaci\u00f3n, la renovaci\u00f3n de la certificaci\u00f3n requer\u00eda estudiar y presentar un examen similar al que se tom\u00f3 para calificar para la certificaci\u00f3n inicial. \u201cEsta oportunidad de UC acent\u00faa a\u00fan m\u00e1s el compromiso y el valor de la educaci\u00f3n de calidad para los profesionales de Tilt-Up de hoy\u201d, dijo Jim Baty, Director T\u00e9cnico de TCA.<\/p>\n<p>\u201cLos superintendentes calificados son la columna vertebral de nuestra empresa. La educaci\u00f3n continua espec\u00edfica de Tilt-Up es muy dif\u00edcil de conseguir, por lo que estoy emocionado de que el TCA nos brinde esta oportunidad en la convenci\u00f3n de oto\u00f1o\u201d, dijo Glenn Doncaster, presidente del TCA.<\/p>\n<p>Otras sesiones planificadas para el personal de construcci\u00f3n en campo incluyen:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.tilt-up.org\/convention\/2012\/programs\/w1\/index.php\">Contratistas Modernos de Tilt-Up: Orgullo y Artesan\u00eda<\/a> por Mitch Bloomquist<\/li>\n<li><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/w2b\/\">C\u00f3mo gestionar, motivar y maximizar la productividad de los equipos de campo<\/a> por George Hedley<\/li>\n<li><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/w4b\/\">Consejos y trucos<\/a> por Barclay Gebel<\/li>\n<li><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/w6\/\">Debate: Del apuntalamiento a la losa<\/a> por Glenn Doncaster<\/li>\n<li><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/t3b\/\">Estudio de caso del proyecto: Museo Nacional de Salud y Medicina<\/a> por David C. Costello<\/li>\n<li><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/t4b\/\">Seguridad de gr\u00faas, arriostramientos y montaje<\/a> por Gary Fischer<\/li>\n<li><a href=\"http:\/\/www.tilt-up.org\/convention\/2012\/programs\/t5b\/index.php\">Control de Calidad y Aseguramiento de Calidad<\/a> por Shawn Hickey<\/li>\n<li><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/t6\/\">Mezclas de Concreto Sostenible: Comprendiendo y Utilizando Cenizas Volantes y Escoria (GGBFS) <\/a> por Andrew McPherson<\/li>\n<li><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/t7\/\">Panel de Discusi\u00f3n: Aprendiendo de Otros \u2013 Mejores Pr\u00e1cticas, Errores Sinceros y Estupideces Simples<\/a> por Shawn Hickey<\/li>\n<\/ul>\n<p>Adem\u00e1s del enfoque en el supervisor de campo, TCA est\u00e1 ofreciendo a los asistentes la oportunidad de participar en comit\u00e9s de la Asociaci\u00f3n asistiendo a una sesi\u00f3n de preguntas y respuestas que se llevar\u00e1 a cabo al inicio de cada reuni\u00f3n de comit\u00e9. El objetivo es presentar el comit\u00e9 y su prop\u00f3sito, as\u00ed como brindar a los asistentes la oportunidad de involucrarse y compartir sus ideas.<\/p>\n<p>Las siguientes reuniones de comit\u00e9 est\u00e1n programadas durante la convenci\u00f3n:<\/p>\n<ul>\n<li>Reuni\u00f3n del Comit\u00e9 de Seguridad: Mi\u00e9rcoles, 3 de octubre de 4 a 5 p. m.<\/li>\n<li>Reuni\u00f3n del Comit\u00e9 de Promociones: Jueves, 4 de octubre de 12 p. m. a 1 p. m.<\/li>\n<li>Reuni\u00f3n del Comit\u00e9 T\u00e9cnico: Jueves, 4 de octubre de 12 p. m. a 1 p. m.<\/li>\n<li>Reuni\u00f3n del Comit\u00e9 de Membres\u00eda: Jueves, 4 de octubre de 12:00 p. m. a 1:00 p. m.<\/li>\n<\/ul>\n<p>La Convenci\u00f3n TCA comenzar\u00e1 el martes 2 de octubre con demostraciones de productos al aire libre y una recepci\u00f3n de bienvenida. La informaci\u00f3n espec\u00edfica de las sesiones para el mi\u00e9rcoles y jueves se puede encontrar visitando <a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/2012\/programs\/\">http:\/\/www.tilt-up.org\/convention\/2012\/programs\/<\/a>. Se realizar\u00e1 una salida de golf el viernes. Para m\u00e1s informaci\u00f3n, visite <a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/convention\/\">www.tilt-up.org\/convention<\/a>.<\/p>\n<p>Hanley Wood es el patrocinador medi\u00e1tico oficial de la Convenci\u00f3n.<\/p>\n<h5><strong><em>Acerca de la TCA<\/em><\/strong><\/h5>\n<p><em>La TCA se fund\u00f3 en 1986 con el objetivo de mejorar la calidad y la aceptaci\u00f3n de la construcci\u00f3n \u00abtilt-up\u00bb (moldeado in situ), un m\u00e9todo de construcci\u00f3n en el que los paneles de hormig\u00f3n para paredes se moldean en la obra y se colocan en su sitio mediante inclinaci\u00f3n. La construcci\u00f3n \u00abtilt-up\u00bb es uno de los sectores de m\u00e1s r\u00e1pido crecimiento en los Estados Unidos, ya que combina las ventajas de un costo razonable con un bajo mantenimiento, durabilidad, rapidez de construcci\u00f3n y una inversi\u00f3n de capital m\u00ednima. Para obtener m\u00e1s informaci\u00f3n sobre la TCA, visite <\/em><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/\"><em>www.tilt-up.org<\/em><\/a><em>, ll\u00e1manos al 319-895-6911, o env\u00eda un correo electr\u00f3nico a <a href=\"mailto:info@tilt-up.org\">info@tilt-up.org<\/a>. <\/em><\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">La Asociaci\u00f3n de Hormig\u00f3n Tilt-Up (TCA) ha anunciado la incorporaci\u00f3n de la Dra. Kim Basham, ingeniera profesional, al programa de la Convenci\u00f3n de la TCA de 2012. Basham, presidenta de KB Engineer, LLC, presentar\u00e1 \u201cControl de grietas en losas\u201d, una sesi\u00f3n centrada en <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2012\/08\/13\/tilt-up-concrete-association-announces-new-speaker-to-round-out-convention-presentations\/\" title=\"La Asociaci\u00f3n de Hormig\u00f3n Tilt-Up anuncia un nuevo ponente para completar el programa de ponencias de la convenci\u00f3n\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":2,"featured_media":1724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,6,7],"tags":[34,73,85],"class_list":["post-1723","post","type-post","status-publish","format-standard","has-post-thumbnail","category-events","category-industry","category-tca_announcements","tag-convention","tag-education-2","tag-troubleshooting"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=1723"}],"version-history":[{"count":16,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1723\/revisions"}],"predecessor-version":[{"id":14517,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1723\/revisions\/14517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/1724"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=1723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=1723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=1723"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}