{"id":1713,"date":"2012-08-07T09:20:12","date_gmt":"2012-08-07T14:20:12","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=1713"},"modified":"2015-06-08T02:37:55","modified_gmt":"2015-06-08T07:37:55","slug":"ardex-mc%e2%84%a2-moisture-control-systems-establish-new-benchmark-for-rh-and-perm-rating","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2012\/08\/07\/ardex-mc%e2%84%a2-moisture-control-systems-establish-new-benchmark-for-rh-and-perm-rating\/","title":{"rendered":"Los Sistemas de Control de Humedad ARDEX MC\u2122 establecen un nuevo est\u00e1ndar para la humedad relativa y la tasa de permeabilidad"},"content":{"rendered":"<p><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/08\/image012.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1714\" title=\"imagen012\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/08\/image012.jpg\" alt=\"\" width=\"129\" height=\"175\" \/><\/a><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/members\/member_card.php\/?id=10153\" target=\"_blank\">ARDEX Am\u00e9ricas<\/a>, conocido por establecer est\u00e1ndares en productos de preparaci\u00f3n de subsuelo, anunci\u00f3 mejoras significativas en los productos ARDEX MC\u2122 Moisture Control Systems. \u201cLos tres sistemas de remediaci\u00f3n de humedad ARDEX, MC\u2122 RAPID, MC\u2122 PLUS y MC\u2122 ULTRA, tienen una calificaci\u00f3n de permeancia de humedad de 0.1 o menos seg\u00fan ASTM E 96\u201d, dijo Bruce Newbrough, Director de Aplicaci\u00f3n y Desarrollo de ARDEX Am\u00e9ricas. Agreg\u00f3: \u201cLos tres sistemas ARDEX MC tambi\u00e9n est\u00e1n ahora clasificados para 100% RH (sin agua estancada)\u201d. Consistente con los cambios de ASTM en la industria, los niveles de rendimiento del producto ARDEX MC\u2122 reflejan el requisito de ASTM para el retardador de vapor debajo de la losa.<\/p>\n<p>\u201dEstos est\u00e1ndares m\u00e1s altos infunden un nivel a\u00fan mayor de confianza en los productos y sistemas ARDEX\u201d, dijo Stephan M. Liozu, presidente y CEO de ARDEX Americas. \u201cTal medida cuantificable de rendimiento eleva el list\u00f3n para un nuevo punto de referencia en la industria para la remediaci\u00f3n de humedad. Combinado con una cobertura de garant\u00eda excepcional, los productos ARDEX son claramente la mejor opci\u00f3n para el \u00e9xito de la instalaci\u00f3n\u201d.\u201d<\/p>\n<p>Para preguntas adicionales, comun\u00edquese con el Departamento T\u00e9cnico de ARDEX al (888) 512-7339 o visite www.ardexamericas.com para obtener informaci\u00f3n completa del producto.<\/p>\n<h5>Acerca de ARDEX<\/h5>\n<p>ARDEX es un l\u00edder mundial en el desarrollo, fabricaci\u00f3n y distribuci\u00f3n de productos de construcci\u00f3n especializados de alto rendimiento para todos los aspectos de la preparaci\u00f3n de sustratos, revestimientos de pisos, sistemas de superficies de baldosas y piedra, y concreto arquitect\u00f3nico para aplicaciones comerciales y residenciales. Durante m\u00e1s de 30 a\u00f1os, ARDEX Am\u00e9ricas ha liderado la industria en rendimiento de productos, innovaci\u00f3n y liderazgo t\u00e9cnico en Am\u00e9rica del Norte, Central y del Sur, y la Cuenca del Caribe. ARDEX se enorgullece de brindar un servicio al cliente inigualable, soporte en campo, capacitaci\u00f3n y un compromiso con el crecimiento y la rentabilidad de los negocios de sus clientes. ARDEX Am\u00e9ricas tiene su sede en Aliquippa, Pensilvania, dentro de la regi\u00f3n de Pittsburgh.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">ARDEX Americas, conocida por establecer est\u00e1ndares en la industria de productos para la preparaci\u00f3n de subsuelos, anunci\u00f3 mejoras significativas en los productos de su Sistema de Control de Humedad ARDEX MC\u2122. \u201cLos tres sistemas de remediaci\u00f3n de humedad ARDEX, MC\u2122 RAPID, MC\u2122 PLUS y MC\u2122 ULTRA, han <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2012\/08\/07\/ardex-mc%e2%84%a2-moisture-control-systems-establish-new-benchmark-for-rh-and-perm-rating\/\" title=\"Los Sistemas de Control de Humedad ARDEX MC\u2122 establecen un nuevo est\u00e1ndar para la humedad relativa y la tasa de permeabilidad\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":2,"featured_media":1153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1713","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=1713"}],"version-history":[{"count":12,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1713\/revisions"}],"predecessor-version":[{"id":7357,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1713\/revisions\/7357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/1153"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=1713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=1713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=1713"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}