{"id":17101,"date":"2023-09-22T08:46:53","date_gmt":"2023-09-22T13:46:53","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=17101"},"modified":"2025-06-17T13:31:03","modified_gmt":"2025-06-17T18:31:03","slug":"records-rotos","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2023\/09\/22\/records-rotos\/","title":{"rendered":"R\u00e9cords rotos"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2023\/09\/22\/broken-records\/\"><strong>Ingl\u00e9s<\/strong><\/a> | Traducci\u00f3n proporcionada por la TCA<\/p>\n<\/div>\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2019\/11\/IMG_9591-2-r-1-768x1024.jpg\" alt=\"\" class=\"wp-image-14271\" width=\"243\" height=\"325\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2019\/11\/IMG_9591-2-r-1-768x1024.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2019\/11\/IMG_9591-2-r-1-225x300.jpg 225w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, tuve la oportunidad de estar en un sitio de trabajo en Lebanon, Kentucky, para observar un hito significativo en la industria de la construcci\u00f3n tilt-up. Como Director Ejecutivo de la Asociaci\u00f3n Tilt-Up Concrete, fue educativo y gratificante estar al lado de algunos de los expertos m\u00e1s conocedores del campo. Juntos, vimos una gr\u00faa de 880 toneladas levantar con \u00e9xito un panel tilt-up aislado de 91 pies. El logro no fue solo un nuevo r\u00e9cord; marc\u00f3 una progresi\u00f3n constante y continua en lo que nuestra industria puede lograr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es casi parad\u00f3jico que el t\u00e9rmino \u201cdisco rayado\u201d signifique monoton\u00eda y repetici\u00f3n en el lenguaje cotidiano. Sin embargo, en este contexto, batir r\u00e9cords es emblem\u00e1tico de la innovaci\u00f3n y el progreso. Y aqu\u00ed radica la iron\u00eda: nos encontramos sonando como un \u201cdisco rayado\u201d cada vez que anunciamos que hemos batido otro r\u00e9cord (panel m\u00e1s alto, panel m\u00e1s ancho, proyecto m\u00e1s grande, panel m\u00e1s pesado, etc.). Pero lejos de ser repetitivo o estancado, cada nuevo hito sirve como un marcador distintivo en la l\u00ednea de tiempo de nuestra industria. Estos r\u00e9cords rotos no son ecos del pasado, m\u00e1s bien amplifican nuestros logros colectivos, catalizando una mayor innovaci\u00f3n y preparando el escenario para el pr\u00f3ximo salto adelante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/09\/DJI_0688-b.jpg\" alt=\"\" class=\"wp-image-17096\" width=\"664\" height=\"559\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Me gustar\u00eda reconocer a Barclay Gebel, miembro de TCA y expresidente, cuya compa\u00f1\u00eda estuvo detr\u00e1s de este esfuerzo. Barclay tiene una historia rica en nuestra industria, habiendo comenzado su carrera como aprendiz de carpintero hace 35 a\u00f1os. Su trabajo y el de su equipo contribuyen a la historia m\u00e1s amplia de la evoluci\u00f3n de la construcci\u00f3n tilt-up.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una era de conciencia ambiental, logros como los paneles Tilt-up m\u00e1s altos o m\u00e1s pesados podr\u00edan malinterpretarse como un exceso. En realidad, estos r\u00e9cords significan eficiencia e ingenio. A medida que los paneles se vuelven m\u00e1s altos, m\u00e1s pesados y m\u00e1s anchos, es una indicaci\u00f3n de que nuestros sistemas se est\u00e1n consolidando y nuestros materiales est\u00e1n cada vez m\u00e1s optimizados. El Tilt-up es cada vez m\u00e1s r\u00e1pido, m\u00e1s \u00e1gil y m\u00e1s vers\u00e1til; cada r\u00e9cord es un testimonio de estos avances incrementales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/09\/DJI_0790-b.jpg\" alt=\"\" class=\"wp-image-17098\" width=\"680\" height=\"453\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/09\/DJI_0790-b.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/09\/DJI_0790-b-300x200.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/09\/DJI_0790-b-768x512.jpg 768w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A todos los que han participado en este logro notable, extiendo mis felicitaciones. Si bien este r\u00e9cord es parte de una trayectoria continua en lugar de un avance repentino, representa un punto notable en el camino de mejora continua de nuestra industria. Nos recuerda que, si bien los hitos individuales pueden superarse, el progreso colectivo que representan contin\u00faa avanzando sin tregua.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">English | Translation Provided by the TCA\nRecently, I had the opportunity to be on a job site in Lebanon, Kentucky, to observe a significant milestone in the tilt-up construction industry. As <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2023\/09\/22\/records-rotos\/\" title=\"R\u00e9cords rotos\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":14270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-17101","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/17101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=17101"}],"version-history":[{"count":2,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/17101\/revisions"}],"predecessor-version":[{"id":17230,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/17101\/revisions\/17230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/14270"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=17101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=17101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=17101"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}