{"id":16975,"date":"2023-06-13T16:18:51","date_gmt":"2023-06-13T21:18:51","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=16975"},"modified":"2025-10-28T10:57:10","modified_gmt":"2025-10-28T15:57:10","slug":"icon23","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2023\/06\/13\/icon23\/","title":{"rendered":"ICON23"},"content":{"rendered":"<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/Icon-Logo.jpg\" alt=\"\" class=\"wp-image-16976\" width=\"680\" height=\"137\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/Icon-Logo.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/Icon-Logo-300x60.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/Icon-Logo-768x155.jpg 768w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, invitados se reunieron para cenar, rodeados de algunos de los paneles de muros de concreto prefabricado (tilt-up) m\u00e1s antiguos e importantes del planeta, en la Cena Inaugural de \u00cdconos de TCA en el La Jolla Woman's Club. Jeffrey Brown, FAIA, FTCA, de Powers Brown Architecture, habl\u00f3 sobre la importancia de la estructura y c\u00f3mo el proyecto contin\u00faa influyendo en las pr\u00e1cticas de dise\u00f1o y construcci\u00f3n hoy en d\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cena y el evento de narraci\u00f3n de historias estuvieron en el centro de una serie de recorridos por la zona que exploraron obras ic\u00f3nicas de arquitectura con muros de concreto y de concreto prefabricado, organizados por UC San Diego, Gensler, Lake|Flato Architects, HGW Architecture y Francis Parker School.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los invitados llegaron el 29 de marzo y realizaron un tour privado guiado por un curador del famoso Salk Institute for Biological Studies. El Instituto Salk ha sido descrito como uno de los sitios arquitect\u00f3nicos m\u00e1s significativos de los Estados Unidos y ha recibido elogios por su dise\u00f1o y preservaci\u00f3n. Los edificios originales de Salk, dise\u00f1ados a principios de la d\u00e9cada de 1960 por el eminente arquitecto estadounidense Louis Kahn en colaboraci\u00f3n con el fundador Jonas Salk, fueron declarados monumento hist\u00f3rico en 1991. Al tour le sigui\u00f3 una recepci\u00f3n en el Hotel La Valencia, un reconocido hito en la distintiva Prospect Street de La Jolla, dominando los acantilados del pueblo con vistas panor\u00e1micas de la costa del Pac\u00edfico y la hermosa Cala de La Jolla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de la Icon Dinner el 30 de marzo, los invitados recorrieron tres edificios galardonados de la Universidad de California en San Diego. \u201cMe sent\u00ed feliz de participar en un di\u00e1logo con socios de la industria y de ofrecer recorridos con nuestros colegas de Francis Parker\u201d, dijo Matthew Smith, arquitecto del Programa de Gesti\u00f3n de Capitales (CPM) de UC San Diego. \u201cLa construcci\u00f3n con moldes prefabricados (tilt-up) nos ha brindado oportunidades en el campus que no habr\u00edan funcionado con concreto colado en sitio o mamposter\u00eda, y nuestros equipos de dise\u00f1o y constructores manejaron estas oportunidades maravillosamente, entregando un dise\u00f1o curado en plazos y presupuestos ambiciosos\u201d.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ARCHITECT Magazine present\u00f3 recientemente los proyectos en una sesi\u00f3n de estudio organizada por Paul Makovsky, editor en jefe de ARCHITECT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento concluy\u00f3 con un recorrido por el campus de Francis Parker School, una escuela preparatoria privada, independiente, coeducacional y diurna para estudiantes desde preescolar menor hasta el grado 12. \u201cCuando la gente visita el Campus Linda Vista de Parker, queda asombrada con los hermosos edificios\u201d, dijo Michael Cain, director de seguridad, salud ambiental y seguridad de Francis Parker School. \u201cPocas personas aprecian los medios y m\u00e9todos utilizados para crear un espacio tan hermoso. El evento reuni\u00f3 a arquitectos, ingenieros, representantes del propietario y contratistas en el mismo lugar y al mismo tiempo. Crear un espacio para conversar con personas de otra disciplina ayuda a avanzar en el trabajo realizado en el campo, desde el dise\u00f1o hasta la postocupaci\u00f3n\u201d.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-P29-792x1024.jpg\" alt=\"\" class=\"wp-image-16982\" width=\"680\" height=\"879\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-P29-792x1024.jpg 792w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-P29-232x300.jpg 232w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-P29-768x993.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2023\/06\/31-1-P29.jpg 1024w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las futuras iteraciones del evento est\u00e1n siendo planificadas para 2025 y 2027.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Recientemente, los invitados se reunieron para cenar \u2014rodeados de algunos de los paneles de pared prefabricados m\u00e1s antiguos e importantes del planeta\u2014 en la cena inaugural \u00abIcon Dinner\u00bb de la TCA, celebrada en el La Jolla Woman\u2019s Club. Jeffrey Brown, FAIA, FTCA, de Powers Brown Architecture, habl\u00f3 sobre <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2023\/06\/13\/icon23\/\" title=\"ICON23\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":16976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[375,6,29],"tags":[],"class_list":["post-16975","post","type-post","status-publish","format-standard","has-post-thumbnail","category-community-culture","category-industry","category-news"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=16975"}],"version-history":[{"count":7,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16975\/revisions"}],"predecessor-version":[{"id":19073,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16975\/revisions\/19073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/16976"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=16975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=16975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=16975"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}