{"id":16655,"date":"2022-12-19T09:14:58","date_gmt":"2022-12-19T14:14:58","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=16655"},"modified":"2025-10-28T11:02:44","modified_gmt":"2025-10-28T16:02:44","slug":"tilt-up-certification-assures-quality-expertise-performance","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2022\/12\/19\/tilt-up-certification-assures-quality-expertise-performance\/","title":{"rendered":"La Certificaci\u00f3n Tilt-Up Asegura Calidad, Experiencia y Rendimiento"},"content":{"rendered":"<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/12\/Dayton-FC-logo-1024x306.jpg\" alt=\"\" class=\"wp-image-16657\" width=\"375\" height=\"112\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/12\/Dayton-FC-logo-1024x306.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/12\/Dayton-FC-logo-300x90.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/12\/Dayton-FC-logo-768x229.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/12\/Dayton-FC-logo-1536x458.jpg 1536w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2022\/12\/Dayton-FC-logo-2048x611.jpg 2048w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RESUMEN<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2021, en un esfuerzo colaborativo entre Dayton Superior y la TCA, se otorgaron casi 150 nuevas certificaciones en la industria Tilt-Up. Entre estos beneficiarios se encontraba Dreamworks Contractors, con sede en Utah.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que abrieron sus puertas en 2018, Dreamworks Contractors ha servido a la industria de la construcci\u00f3n como una fuente de dise\u00f1o y construcci\u00f3n, gesti\u00f3n de la construcci\u00f3n y planificaci\u00f3n de la construcci\u00f3n. Su alcance de trabajo incluye residencias personalizadas, mejoras para inquilinos y proyectos comerciales desde cero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que recibieron su Certificaci\u00f3n de T\u00e9cnico de Tilt-Up de la ACI a principios de este a\u00f1o, Dreamworks Contractors ha sido galardonada con m\u00faltiples proyectos de tilt-up. Con el nivel de desempe\u00f1o garantizado por la certificaci\u00f3n, sabemos que habr\u00e1 m\u00e1s proyectos de tilt en su futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El poder de la certificaci\u00f3n no solo fortalece a tu equipo, sino tambi\u00e9n a la industria de la inclinaci\u00f3n en su conjunto. La importancia de servir al propietario del edificio y la capacidad de brindar experiencia \u2014incluidas las conversaciones iniciales en el proceso de construcci\u00f3n y estimaci\u00f3n\u2014 es imperativa y construye relaciones de confianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INFORMACI\u00d3N DE PRUEBA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oportunidades de capacitaci\u00f3n y examen presenciales o virtuales para el tilt-up<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">industria est\u00e1n disponibles. Mediante una combinaci\u00f3n de instrucci\u00f3n y administraci\u00f3n de ex\u00e1menes virtual y presencial, las empresas pueden recibir empleados en sus propias instalaciones para el curso preparatorio de certificaci\u00f3n Tilt-Up 101 y el Supervisor y<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Examen de Certificaci\u00f3n T\u00e9cnica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Superior Tilt y la Tilt-Up Concrete Association se enorgullecen de ofrecer este servicio. Visite tilt-up.org\/events para obtener m\u00e1s informaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo del programa de certificaci\u00f3n Tilt-Up es ofrecer a los propietarios, especificadores y dise\u00f1adores un m\u00e9todo para garantizar la experiencia, la calidad y el rendimiento de los contratistas de concreto prefabricado.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">RESUMEN En 2021, en un esfuerzo colaborativo entre Dayton Superior y la TCA, se otorgaron casi 150 nuevas certificaciones en la industria Tilt-Up. Entre estos destinatarios se encontraban Dreamworks Contractors, con sede en Utah. Desde que abrieron sus puertas en <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2022\/12\/19\/tilt-up-certification-assures-quality-expertise-performance\/\" title=\"La Certificaci\u00f3n Tilt-Up Asegura Calidad, Experiencia y Rendimiento\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":16657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,387],"tags":[],"class_list":["post-16655","post","type-post","status-publish","format-standard","has-post-thumbnail","category-member_news","category-workforce-training-industry"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=16655"}],"version-history":[{"count":6,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16655\/revisions"}],"predecessor-version":[{"id":19089,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16655\/revisions\/19089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/16657"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=16655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=16655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=16655"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}