{"id":16063,"date":"2021-12-20T15:57:33","date_gmt":"2021-12-20T20:57:33","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=16063"},"modified":"2025-10-28T11:20:04","modified_gmt":"2025-10-28T16:20:04","slug":"tca-journal-call-for-manuscripts","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/12\/20\/tca-journal-call-for-manuscripts\/","title":{"rendered":"Revista TCA \u2013 Convocatoria de art\u00edculos"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"456\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/12\/MANUSCRIPTS-r-.jpg\" alt=\"\" class=\"wp-image-16065\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/12\/MANUSCRIPTS-r-.jpg 680w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/12\/MANUSCRIPTS-r--300x201.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para enviar un manuscrito<\/strong> a la revista TCA, por favor lea y siga las directrices a continuaci\u00f3n. Los manuscritos completos en formato PDF se pueden enviar por correo electr\u00f3nico durante todo el a\u00f1o a <a href=\"mailto:timothy.mays@citadel.edu\" target=\"_blank\" rel=\"noreferrer noopener\">timothy.mays@citadel.edu<\/a> (Timothy W. Mays, Ph.D., P.E. , Editor T\u00e9cnico de la TCA Journal). Los manuscritos deben tener menos de 8,000 palabras, y cualquier figura o tabla se considerar\u00e1 de 300 palabras cada una al verificar el recuento de palabras. Los manuscritos deben incluir las siguientes secciones: T\u00edtulo, Autor(es), Resumen, Introducci\u00f3n, Cuerpo (var\u00eda), Conclusiones, Agradecimientos, Referencias, Notaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TCA acusar\u00e1 recibo de su manuscrito en el plazo de una semana. Un comit\u00e9 de revisi\u00f3n con experiencia relacionada con el contenido de su manuscrito revisar\u00e1 la propuesta y proporcionar\u00e1 comentarios individuales an\u00f3nimos al autor a trav\u00e9s del editor t\u00e9cnico. La revisi\u00f3n por pares normalmente tarda de dos a tres meses en completarse. Las recomendaciones del comit\u00e9 de revisi\u00f3n al editor t\u00e9cnico se utilizar\u00e1n para determinar si el manuscrito es aceptado y su fecha de publicaci\u00f3n programada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que un art\u00edculo ha sido aceptado para su publicaci\u00f3n, se le pedir\u00e1 al autor que env\u00ede archivos individuales de figuras con calidad y tama\u00f1o espec\u00edficos para cumplir con el est\u00e1ndar de calidad de la revista.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Convocatoria de Seminarios<\/h1>\n\n\n\n<h3 class=\"wp-block-heading\">Habla en la Convenci\u00f3n y Expo Tilt-Up 2022<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Tilt-Up Convention and Expo se dirige a Denver, Colorado, en 2022 y queremos escucharte. Si eres un experto en dise\u00f1o, ingenier\u00eda, construcci\u00f3n o tecnolog\u00eda de tilt-up y tienes una idea para un seminario, te invitamos a presentar una propuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las propuestas son evaluadas por el comit\u00e9 de educaci\u00f3n de la TCA&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Convocatoria de Seminarios: Fechas l\u00edmite<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>4 de febrero: Cierre de convocatorias para seminarios a las 23:59 (Hora Central)<\/li><li>4 de marzo: Notificaci\u00f3n de aceptaci\u00f3n&nbsp;<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">C\u00f3mo enviar<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Visita tilt-up.org\/events y env\u00eda por correo electr\u00f3nico el t\u00edtulo propuesto para tu seminario, un resumen y cuatro objetivos de aprendizaje a <a href=\"mailto:mbloomquist@tilt-up.org\" target=\"_blank\" rel=\"noreferrer noopener\">mbloomquist@tilt-up.org<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Para enviar un manuscrito a la revista TCA Journal, le rogamos que lea y siga las siguientes directrices. Los manuscritos completos en formato PDF pueden enviarse por correo electr\u00f3nico durante todo el a\u00f1o a timothy.mays@citadel.edu (Timothy W. Mays, Ph.D., P.E., responsable t\u00e9cnico de la revista TCA Journal <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/12\/20\/tca-journal-call-for-manuscripts\/\" title=\"Revista TCA \u2013 Convocatoria de art\u00edculos\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":16065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-16063","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tca_announcements"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=16063"}],"version-history":[{"count":5,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16063\/revisions"}],"predecessor-version":[{"id":19132,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/16063\/revisions\/19132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/16065"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=16063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=16063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=16063"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}