{"id":15901,"date":"2021-12-20T16:43:52","date_gmt":"2021-12-20T21:43:52","guid":{"rendered":"https:\/\/tilt-up.org\/tilt-uptoday\/?p=15901"},"modified":"2025-06-17T10:48:47","modified_gmt":"2025-06-17T15:48:47","slug":"facilitar-la-accion-comunitaria","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/12\/20\/facilitar-la-accion-comunitaria\/","title":{"rendered":"FACILITAR LA ACCI\u00d3N COMUNITARIA"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/12\/20\/facilitating-community-action\/\"><strong>Ingl\u00e9s<\/strong><\/a> | Traducci\u00f3n patrocinada por <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de productos Nox-Crete<\/a><\/p>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">\u201cHe observado a la comunidad como la unidad de organizaci\u00f3n social en donde reside el elemento m\u00e1s grande de esperanza para un progreso permanente\u201d.<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2019\/11\/IMG_9591-2-r-768x1024.jpg\" alt=\"\" class=\"wp-image-14270\" width=\"190\" height=\"253\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2019\/11\/IMG_9591-2-r-768x1024.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2019\/11\/IMG_9591-2-r-225x300.jpg 225w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la reuni\u00f3n virtual de octubre de 2020, escrib\u00ed una carta exponiendo la importancia de ser una comunidad. A primera vista, es obvio y podr\u00eda desestimarse como ret\u00f3rica promocional, pero para m\u00ed, la idea de comunidad sigue estando al frente de mi trabajo con esta asociaci\u00f3n. Soy de coraz\u00f3n un organizador comunitario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eduard C. Lindeman pronunci\u00f3 la definici\u00f3n de una organizaci\u00f3n comunitaria en 1921 como \u201cEsas dos fases de organizaci\u00f3n social que constituyen un esfuerzo consciente por parte de una comunidad para controlar democr\u00e1ticamente sus asuntos y asegurar los m\u00e1s altos servicios de sus especialistas, organizaciones, agencias e instituciones por medio de interrelaciones reconocidas\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comparto esta definici\u00f3n con ustedes para destacar dos elementos importantes: el primero es que nuestro esfuerzo tiene un objetivo. Dicho de otra manera, trabajamos intencionalmente para servir a nuestra industria y unos a otros m\u00e1s all\u00e1 de lo que se esperar\u00eda de colaboraciones casuales y esfuerzos individuales. Segundo, hacemos esto a trav\u00e9s de una colaboraci\u00f3n program\u00e1tica, es decir, actividades planificadas dirigidas a destacar la manera en las que nuestro trabajo nos afecta unos a otros. Dependemos de estas interacciones para identificar las necesidades de la comunidad y a su vez desarrollar soluciones como una comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si estuvo en St. Louis este pasado septiembre para la convenci\u00f3n, escuch\u00f3 a Barclay Gebel, FTCA, compartir la necesidad de considerar una capacidad de subrasante relacionada con las cargas del suelo de apoyo de la gr\u00faa durante la construcci\u00f3n. En ese momento, Barclay propuso un lenguaje para una declaraci\u00f3n colectiva de la industria, y los m\u00e1s de 400 profesionales en la sala aprovecharon la oportunidad para hacer comentarios y conversar sobre ello. Hubo una invitaci\u00f3n por parte de Chad Bruce, quien present\u00f3 los problemas con el uso de adhesivos en losas de diferente energ\u00eda superficial, para unirse a una investigaci\u00f3n. Se present\u00f3 el trabajo del Dr. Maguire y un grupo de ingenieros y fabricantes de conectores de paneles compuestos. Finalmente, un grupo de profesionales j\u00f3venes comparti\u00f3 historias sobre el empleo de su generaci\u00f3n y la cultura en el lugar de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La raz\u00f3n por la que menciono estos momentos es para declarar nuevamente que esto es el trabajo de nuestra comunidad. La TCA no existe como una entidad remota que opera de manera an\u00f3nima a favor de la industria. Organizaciones como esta solo existen a trav\u00e9s de la participaci\u00f3n activa de sus miembros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joseph K. Hart escribi\u00f3 sobre el rol del organizador comunitario al facilitar esta funci\u00f3n que: \u201cEsta tarea de la organizaci\u00f3n comunitaria implica el desarrollo de un orden social lo suficientemente inclusivo, rico, variado y estimulante como para llegar a todos los seres humanos normales\u201d. Con ese fin, nos hemos concentrado en una programaci\u00f3n que mejora el acceso a recursos multidisciplinarios de la TCA. Una programaci\u00f3n que nos conecta para compartir historias, debatir, celebrar e innovar. A medida que nos acercamos al nuevo a\u00f1o, animo a todos a volver a comprometerse con esta comunidad a trav\u00e9s de una participaci\u00f3n activa. Inicia sesi\u00f3n, inscr\u00edbete, haz acto de presencia. S\u00e9 parte de la comunidad. El trabajo m\u00e1s significativo y de mayor impacto provendr\u00e1 de nuestra voz colectiva, rica en inclusividad y diversas experiencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saludos cordiales,<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"78\" src=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2018\/01\/Mitch-Bloomquist-Signature-SML-G-R.jpg\" alt=\"\" class=\"wp-image-8939\"\/><\/figure>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">\u201cHE OBSERVADO A LA COMUNIDAD COMO LA UNIDAD DE ORGANIZACI\u00d3N SOCIAL EN DONDE RESIDE EL ELEMENTO M\u00c1S GRANDE DE ESPERANZA PARA UN PROGRESO PERMANENTE\u201d. Despu\u00e9s de la <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/12\/20\/facilitar-la-accion-comunitaria\/\" title=\"FACILITAR LA ACCI\u00d3N COMUNITARIA\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":14270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-15901","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=15901"}],"version-history":[{"count":2,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15901\/revisions"}],"predecessor-version":[{"id":16153,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15901\/revisions\/16153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/14270"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=15901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=15901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=15901"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}