{"id":15798,"date":"2021-08-26T15:33:39","date_gmt":"2021-08-26T20:33:39","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=15798"},"modified":"2025-06-17T10:27:11","modified_gmt":"2025-06-17T15:27:11","slug":"tilt-up-newburyport","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/08\/26\/tilt-up-newburyport\/","title":{"rendered":"TILT-UP, NEWBURYPORT"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/08\/26\/tilt-up-newburyport-2\/\"><strong>Ingl\u00e9s<\/strong><\/a> | Traducci\u00f3n patrocinada por <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de productos Nox-Crete<\/a><\/p>\n<\/div>\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-8R.jpg\" alt=\"\" class=\"wp-image-15792\" width=\"680\" height=\"384\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-8R.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-8R-300x169.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-8R-768x434.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-8R-600x340.jpg 600w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-8R-640x360.jpg 640w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Newburyport, Massachusetts, una hist\u00f3rica ciudad mar\u00edtima yanqui situada al norte de Boston, parece un lugar poco probable para una revoluci\u00f3n en la construcci\u00f3n. Sin embargo, aqu\u00ed, en el Hillside Center for Sustainable Living, un nuevo pueblo de cuarenta y ocho viviendas y dos acres de huertos comestibles, representa una nueva propuesta de vida sustentable. Hillside est\u00e1 utilizando uno de los materiales de construcci\u00f3n m\u00e1s antiguos de una manera nueva y actualizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los desarrolladores del proyecto, David Hall y Keith Moskow, son tambi\u00e9n el constructor y arquitecto de la villa y ambos son experimentadores intr\u00e9pidos. El sitio de cinco acres es un lote bald\u00edo rehabilitado y aunque el proyecto terminado eventualmente llegar\u00e1 a casi cero emisiones netas, Hillside hace mucho m\u00e1s que simplemente combatir el cambio clim\u00e1tico. Ser\u00e1 autosustentable, econ\u00f3mico y fabricado con una t\u00e9cnica de construcci\u00f3n comercial a gran escala adaptada aqu\u00ed para uso residencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera fase de Hillside est\u00e1 completa y totalmente ocupada, mientras que una YWCA con diez habitaciones individuales y un edificio de ocho unidades est\u00e1n en construcci\u00f3n. Para completar la villa de casas de una, dos y tres habitaciones, habr\u00e1 una casa com\u00fan, un granero comunitario, un invernadero y parcelas para cultivo individuales. Las unidades cumplen con las normas pasivas de vivienda y tendr\u00e1n certificaci\u00f3n LEED platino. La energ\u00eda solar generada en Hillside excede todas las necesidades de energ\u00eda de la villa, incluyendo la energ\u00eda para la flotilla comunitaria de autos el\u00e9ctricos. El agua de lluvia de los techos fluye hacia las cisternas que est\u00e1n debajo del invernadero y se bombea para los sanitarios y para irrigar los cultivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a la propuesta-adquisici\u00f3n, permisos, dise\u00f1o, construcci\u00f3n, propiedad, alquiler y mantenimiento completamente integrados, Hall y Moskow pudieron hacer que los alquileres fueran econ\u00f3micos y autosustentables. Pero, estos objetivos que ponen al frente el clima no habr\u00edan sido posibles sin el sistema \u00fanico de ensamblaje llamado construcci\u00f3n de muros premoldeados. (Tambi\u00e9n se debe dar cr\u00e9dito a los funcionarios de construcci\u00f3n de Newburyport que alentaron este proyecto tan inusual). El sistema prefabricado es com\u00fan en las estructuras comerciales grandes, tales como almacenes gigantes y edificios de oficinas grandes, pero, como lo indica Hall, es muy inusual en dise\u00f1o residencial. Moskow dice que el desaf\u00edo de crear Hillside es \u201cun proyecto emocionante para nosotros, es arquitectura con \u2018a\u2019 min\u00fascula\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/IMG_2016-R-768x1024.jpg\" alt=\"\" class=\"wp-image-15794\" width=\"680\" height=\"907\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/IMG_2016-R-768x1024.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/IMG_2016-R-225x300.jpg 225w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/IMG_2016-R.jpg 1024w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El m\u00e9todo Tilt-up consiste en paneles de muro de concreto que se vac\u00edan in situ en moldes de espuma EPS especialmente dise\u00f1ados y luego se levantan con una gr\u00faa para colocarlos en posici\u00f3n vertical y formar los muros. Se utiliza acero para unir los muros y las uniones se sellan con poliestireno. En resumen, se reducen los costos de tiempo de construcci\u00f3n, as\u00ed como los de materiales y transporte. Es dif\u00edcil imaginar una forma de construir casas con menos pasos y menos equipo. Los paneles de concreto son esencialmente acumuladores t\u00e9rmicos, lo que se traduce en un gran ahorro en calefacci\u00f3n. Adem\u00e1s, tener muros de solo concreto y no reforzados con acero permite una geometr\u00eda repetible pero m\u00e1s compleja para las aberturas que las estructuras tradicionales. A diferencia de la idea que tiene la mayor\u00eda de la gente de que el concreto es fr\u00edo y abrasivo, las superficies de concreto interiores est\u00e1n enlucidas. Las paredes de madera y listones de las caba\u00f1as de Hillside son atractivas; son casas en las que a la mayor\u00eda de las personas les gustar\u00eda vivir. Las casas tienen \u2018porches de granjero\u2019 con mecedoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El concreto es un material de uso tan vasto que puede crear belleza extrema o resolver necesidades humanitarias, pero se tiene que manejar cuidadosamente. Si un constructor es flojo con el concreto, har\u00e1 edificios que envejecer\u00e1n de manera deficiente y todos, salvo los arquitectos, los odiar\u00e1n. Pero aqu\u00ed, Moskow y Hall han acogido las contradicciones del concreto y han desarrollado su eficacia y funcionalidad para crear algo atractivo y deseable. El tilt-up, como se exhibe en Newburyport, es el h\u00edbrido perfecto de simplicidad y modernidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El uso del tilt-up en el combate contra el cambio clim\u00e1tico representa una contradicci\u00f3n y un desaf\u00edo, ya que la preparaci\u00f3n de cemento requiere quemar cantidades considerables de combustibles f\u00f3siles, lo que libera CO2. Pero el tilt-up tambi\u00e9n puede ser la soluci\u00f3n, porque el desarrollo de la tecnolog\u00eda de captura de carbono en el cemento est\u00e1 mejorando dr\u00e1sticamente (como demostr\u00f3 la compa\u00f1\u00eda Carbon Cure de Nueva Escocia, por ejemplo). Ahora, como demostr\u00f3 el Centro para Vida Sostenible de Hillside, el concreto es durable, sencillo de hacer y puede generar ahorros considerables en energ\u00eda. De la manera que lo formaron Hall y Moskow, tambi\u00e9n es comprobable que es atractivo. Hillside es el resultado de la creencia de dos constructores pr\u00e1cticos y con experiencia que no temen so\u00f1ar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su peque\u00f1o sue\u00f1o de tilt-up es incre\u00edblemente significativo, porque en su materializaci\u00f3n, esta villa de Nueva Inglaterra es un modelo para un futuro econ\u00f3mico, incre\u00edblemente eficaz y f\u00e1cilmente replicable.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-2R.jpg\" alt=\"\" class=\"wp-image-15796\" width=\"680\" height=\"383\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-2R.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-2R-300x169.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-2R-768x432.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/Hillside-Living-LLC-2R-640x360.jpg 640w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Newburyport, Massachusetts, una hist\u00f3rica ciudad portuaria yanqui, al norte de Boston, parece un lugar poco probable para una revoluci\u00f3n en la construcci\u00f3n. Sin embargo, aqu\u00ed, en el Centro <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/08\/26\/tilt-up-newburyport\/\" title=\"TILT-UP, NEWBURYPORT\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":15792,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-15798","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=15798"}],"version-history":[{"count":5,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15798\/revisions"}],"predecessor-version":[{"id":15835,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15798\/revisions\/15835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/15792"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=15798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=15798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=15798"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}