{"id":15749,"date":"2021-08-26T15:40:31","date_gmt":"2021-08-26T20:40:31","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=15749"},"modified":"2025-06-17T10:29:18","modified_gmt":"2025-06-17T15:29:18","slug":"conversacion-con-el-comite-ejecutivo-de-la-tca-2","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/08\/26\/conversacion-con-el-comite-ejecutivo-de-la-tca-2\/","title":{"rendered":"CONVERSACI\u00d3N CON EL COMIT\u00c9 EJECUTIVO DE LA TCA"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/08\/26\/a-conversation-with-tcas-executive-committee\/\"><strong>Ingl\u00e9s<\/strong><\/a> | Traducci\u00f3n patrocinada por <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de productos Nox-Crete<\/a><\/p>\n<\/div>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/GROUP-2Rn.jpg\" alt=\"\" class=\"wp-image-15745\" width=\"680\" height=\"245\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/GROUP-2Rn.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/GROUP-2Rn-300x108.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/08\/GROUP-2Rn-768x277.jpg 768w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El liderazgo dentro de la Tilt-Up Concrete Association<\/strong> consiste en quince personas que sirven en la mesa directiva. Sirven en t\u00e9rminos rotativos de tres a\u00f1os, renovables hasta por dos t\u00e9rminos consecutivos. En estos momentos, ciertos l\u00edderes empiezan a impactar a la asociaci\u00f3n a nivel del comit\u00e9 ejecutivo. Aqu\u00ed, se lleva a cabo una experiencia m\u00e1s regular e intensiva con el personal de TCA para garantizar el mantenimiento de la visi\u00f3n y prop\u00f3sito a lo largo del a\u00f1o calendario. Un presidente de la TCA sirve solo un a\u00f1o y por lo tanto la confianza en la pasi\u00f3n y experiencia de este equipo ejecutivo se magnifica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s una de las cosas m\u00e1s dif\u00edciles de reconocer en una organizaci\u00f3n de la industria como la TCA es el lado personal del liderazgo. A menos que asistas regularmente a los eventos e inviertas en fortalecer relaciones, podr\u00edas no reconocer los rostros y nombres que aportan su car\u00e1cter, estilo de liderazgo y experiencia a la asociaci\u00f3n. Por lo tanto, para dar una mejor identidad a esas personas que aportan tanto a la direcci\u00f3n actual de la asociaci\u00f3n, nuestro director ejecutivo, Mitch Bloomquist, dedic\u00f3 tiempo en un retiro reciente para involucrarlos como grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El comit\u00e9 ejecutivo est\u00e1 integrado por Barclay Gebel (presidente), vicepresidente de Concrete Strategies (St. Louis, Missouri), una subcontratista e instaladora a nivel nacional de paneles tilt-up; Karen Hand (vicepresidenta), presidenta de Needham DBS (Lenexa, Kansas), una firma de ingenier\u00eda a nivel nacional y especializada en ingenier\u00eda tilt-up; Robert Murray (tesorero), vicepresidente y gerente general de Alston Construction Company (Edison, New Jersey), una firma contratista general a nivel nacional; Rick Galloway (secretario), vicepresidente ejecutivo de Martin Concrete Construction (Kennesaw, Georgia), una firma contratista de concreto general especializada en construcci\u00f3n tilt-up; y Scott Bunney (expresidente), presidente de KB Concrete Systems (Commerce City, Colorado), una firma de construcci\u00f3n de concreto regional especializada en construcci\u00f3n tilt-up.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mitch:<\/strong> <em>Gracias por tomarse el tiempo aqu\u00ed en nuestro retiro para pensar en los miembros de la asociaci\u00f3n y ayudarlos a identificarse m\u00e1s f\u00e1cilmente con cada uno de ustedes. Para empezar, \u00bfcu\u00e1l ha sido su inspiraci\u00f3n para contribuir con la industria a trav\u00e9s del servicio en la mesa directiva de la TCA?<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Gebel<\/strong>Toda la gente maravillosa que est\u00e1 activa y pertenece a la TCA me inspira a trabajar en la mesa directiva. Deseo poner de mi parte para hacer que la industria llegue a ser la mejor y que siga creciendo y mejorando para la pr\u00f3xima generaci\u00f3n.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Galloway:<\/strong> La industria me ha dado mucho, tanto a nivel personal como profesional. Las personas que he conocido a trav\u00e9s de mi trabajo en Martin Concrete Construction y la Tilt-up Concrete Association, siguen teniendo un impacto incre\u00edblemente positivo en mi familia y en m\u00ed. Espero poder tener el mismo tipo de impacto constructivo en mis contempor\u00e1neos, mientras apoyo y fomento al pr\u00f3ximo grupo de profesionales que surjan de las filas.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Murray:<\/strong> La industria tilt-up me ha brindado la capacidad de entregar proyectos de dise\u00f1o\/construcci\u00f3n de manera r\u00e1pida y eficiente. Colaborar con los miembros de la asociaci\u00f3n, ya sean proveedores, subcontratistas o incluso competidores, permite el crecimiento colaborativo en la industria y el crecimiento personal de todos los involucrados.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Mano<\/strong> La red de la TCA ha proporcionado un m\u00e9todo para especializarse en un sector del campo de la ingenier\u00eda que es \u00fanico y tiene gran potencial comercial. Las relaciones que he establecido en los \u00faltimos 20 a\u00f1os de participaci\u00f3n en la TCA me han ayudado a impulsar mi carrera profesional. Mi crecimiento como ingeniera, gerente y presidenta no habr\u00eda sido posible sin la trayectoria profesional que me ha brindado la participaci\u00f3n en la TCA. La participaci\u00f3n en la junta directiva y el comit\u00e9 ejecutivo de la TCA ofrece la oportunidad de devolver el favor a la pr\u00f3xima generaci\u00f3n de l\u00edderes.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Conejo<\/strong> Mi inspiraci\u00f3n para retribuir a la industria ha sido que, anteriormente, nuestro mercado local de construcci\u00f3n prefabricada de concreto (tilt-up) ha utilizado este m\u00e9todo como sustituto de otros sistemas y materiales de construcci\u00f3n, en lugar de ser la primera opci\u00f3n. He trabajado mucho para establecer la construcci\u00f3n tilt-up como el m\u00e9todo preferido, y s\u00e9 que un mayor volumen de este tipo de construcciones atraer\u00e1 la atenci\u00f3n e inter\u00e9s en nuestra industria, desde almacenes hasta oficinas de clase \u201cA\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mitch:<\/strong> <em>Gracias por sus aportes. Cada uno de ustedes proviene de una amplia variedad de antecedentes, disciplinas y experiencias en la industria. \u00bfEn qu\u00e9 capacidad sienten que la TCA puede servir mejor para hacer crecer la industria de tilt-up?<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Gebel:<\/strong> Creo que la TCA ofrece un mejor servicio a la industria por su capacidad de crear redes de contactos y organizar eventos y plataformas que re\u00fanen a las personas para aprender y crecer.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Galloway:<\/strong> La Tilt-Up Concrete Association es el \u00fanico grupo profesional que fomenta la colaboraci\u00f3n entre todas las partes interesadas en la industria. Arquitectos, contratistas, ingenieros, proveedores de materiales y otros est\u00e1n representados y tienen una voz igual. Aprovechar la experiencia de estas personas y transmitir ese conocimiento a los l\u00edderes emergentes m\u00e1s j\u00f3venes es esencial para el progreso de nuestra industria. La TCA logra esto a trav\u00e9s de la Academia de Tilt-up, la certificaci\u00f3n de personal y de compa\u00f1\u00edas, programas como las pl\u00e1ticas BigWig Lunch Talks de hace unos a\u00f1os y TILT (Tilt-Up Industry Leaders of Tomorrow), el grupo de liderazgo de profesionales j\u00f3venes.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Murray:<\/strong> La TCA puede servir mejor a la industria del tilt-up manteni\u00e9ndose a la vanguardia y actualizando continuamente las herramientas de la industria. Ofrecer orientaci\u00f3n en el dise\u00f1o y sugerencias de seguridad, as\u00ed como ayudar a mejorar las t\u00e9cnicas de tilt-up, ser\u00e1 de mayor utilidad para el tilt-up a corto plazo y en el futuro.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Mano<\/strong> Atraer inter\u00e9s por los nuevos productos y proveedores y promover el crecimiento de la industria a trav\u00e9s de la comercializaci\u00f3n y publicidad. La TCA es fundamental en la creaci\u00f3n de fuentes de oportunidades de aprendizaje y establecimiento de contactos exclusivas. Una parte esencial de servir a nuestra industria proviene de ampliar nuestro alcance m\u00e1s all\u00e1 de las profundidades de las compa\u00f1\u00edas que han sido parte de la organizaci\u00f3n durante a\u00f1os, as\u00ed como de atraer a nuevos miembros de compa\u00f1\u00edas nuevas para que se capaciten y aprendan m\u00e1s.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Conejo<\/strong> Mediante recursos accesibles y confiables, la TCA ha seguido ampliando, promoviendo y complementando su sitio web, convirti\u00e9ndose en la base de informaci\u00f3n para usuarios nuevos y antiguos del concreto tilt-up. La informaci\u00f3n en l\u00ednea se mantiene siempre actualizada y a la vanguardia para que las ideas nuevas sigan fluyendo en toda la industria. El desarrollo y el trabajo continuo para conservar la industria del tilt-up como una comunidad a trav\u00e9s de la colaboraci\u00f3n grupal, ha sido y seguir\u00e1 siendo una manera significativa de promover el tilt-up. La colaboraci\u00f3n entre todos los grupos de nuestra asociaci\u00f3n comercial es lo que sigue creando nuevas ideas para nuestra industria.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mitch:<\/strong> <em>La TCA ha sido testigo de un tremendo crecimiento y \u00e9xito desde la gran recesi\u00f3n y estamos listos para dirigir el \u00e9xito constante en esta nueva d\u00e9cada. \u00bfCu\u00e1l dir\u00edan que es la m\u00e1s grande oportunidad de crecimiento en nuestra industria?<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Gebel:<\/strong> Creo que la mayor oportunidad de crecimiento en nuestra industria es convencer a las personas y generaciones m\u00e1s j\u00f3venes de que se puede hacer una gran carrera profesional en la industria de tilt-up. La industria de tilt-up \/ concreto sufre carencias en todos los tipos de trabajadores, desde ingenieros hasta oficios. La industria de tilt-up necesita comercializar, reclutar y retener a las mejores y m\u00e1s brillantes personas para mantenerse al d\u00eda con el crecimiento que estamos experimentando.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Galloway:<\/strong> A m\u00ed me emociona el potencial de Tilt Lab para ampliar las maneras en las que la construcci\u00f3n con tilt-up puede encontrar soluciones que no solo enfrentan nuestra industria, sino el cambiante mundo en el que vivimos. Al refinar los detalles y procesos podemos llegar m\u00e1s all\u00e1 del espacio de grandes superficies y continuar la adopci\u00f3n de tilt-up en edificios de oficinas, educativos, institucionales, residenciales y otras estructuras. Podemos seguir creciendo en \u00e1reas geogr\u00e1ficas en las que t\u00edpicamente no vemos estos tipos de construcciones hechas con tilt-up.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Murray:<\/strong> La oportunidad de crecimiento m\u00e1s grande en nuestra industria es transmitir el conocimiento que tenemos a la pr\u00f3xima generaci\u00f3n. Al sumar a la pr\u00f3xima generaci\u00f3n y buscar su participaci\u00f3n e ingenio, tendremos la certeza de estar desarrollando un mejor producto y una mejor organizaci\u00f3n.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Mano<\/strong> El desarrollo de nuevos productos y mejoras en la tecnolog\u00eda que hacen la construcci\u00f3n de paneles tilt-up m\u00e1s eficiente con menos mano de obra.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Conejo<\/strong> La mayor oportunidad existe en incorporar el dise\u00f1o tilt-up donde no se ha considerado posible. Un ejemplo de esta oportunidad podr\u00eda ser en el sector educativo. Adem\u00e1s, est\u00e1 la educaci\u00f3n de desarrolladores, ingenieros y arquitectos en el avance continuo de la tecnolog\u00eda y dise\u00f1o tilt-up.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mitch:<\/strong> <em>Dados sus pensamientos sobre el crecimiento de la industria y sabiendo que la TCA es vista como el proveedor o conservador del medio ambiente al dirigir dicho crecimiento, existen factores clave o temas que est\u00e1n presentes en la primera l\u00ednea. \u00bfCu\u00e1l es el rol de la TCA al abordar cuestiones como la escasez de materiales y mano de obra, la sustentabilidad del cemento y el concreto, y la preparaci\u00f3n para desastres?<\/em>?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Gebel:<\/strong> Creo que la TCA servir\u00eda mejor al problema de escasez de la industria al continuar brindando una plataforma abierta para que todos los que forman parte de la industria de tilt-up hablen sobre el problema y encuentren soluciones.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Galloway:<\/strong> La TCA puede abordar mejor estos temas participando y empoderando a su red de profesionales para que respondan a los problemas a medida que surjan. Tener eventos como las Series de Mesa Redonda y los programas de Future Think en el calendario mantiene a nuestros miembros enfocados en la mejora continua y el progreso. La convenci\u00f3n y exposici\u00f3n anual de tilt-up es un gran indicador de lo que est\u00e1 sucediendo, bueno o malo, en la industria y en la econom\u00eda en general. La serie de seminarios web durante la pandemia fue un gran recurso de informaci\u00f3n y aliento cuando todos ten\u00edan mucha incertidumbre sobre lo que estaba sucediendo, las implicaciones y lo que vendr\u00eda despu\u00e9s. Fue impresionante ver qu\u00e9 tan r\u00e1pida y adecuadamente respondi\u00f3 la asociaci\u00f3n para ayudar a los miembros durante estos tiempos tan dif\u00edciles.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Murray:<\/strong> Aunque abordar temas como la escasez de materiales y mano de obra, la sustentabilidad del cemento y el concreto, y la preparaci\u00f3n ante desastres pueda no ser una funci\u00f3n espec\u00edfica de la TCA, la colaboraci\u00f3n y la conversaci\u00f3n general entre los miembros de la asociaci\u00f3n ciertamente conducir\u00e1n al apoyo mutuo para delinear y abordar los problemas actuales.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Mano<\/strong> Los problemas que impactan a nuestra industria son mundiales y regionales. La TCA cuenta con una gran red de profesionales de la industria, contratistas, arquitectos e ingenieros para atender cada problema a medida que se presenta. El uso de las fortalezas de nuestros miembros permite a la TCA brindar un valioso servicio a la industria.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Conejo<\/strong> El rol de la TCA es ser un recurso, creando una comunidad que empodera a los miembros a colaborar entre s\u00ed para encontrar soluciones \u00fanicas a los desaf\u00edos particulares de cada persona. Sobre la sostenibilidad del cemento y el concreto, el rol de la TCA ha sido su presencia significativa en esta industria, con nuestro considerable uso de concreto, necesitamos poner de nuestra parte para ser parte de la soluci\u00f3n.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mitch:<\/strong> <em>Esto establece una s\u00f3lida plataforma de liderazgo para TCA o esta junta directiva, as\u00ed como para quienes vendr\u00e1n despu\u00e9s de ustedes. \u00bfQu\u00e9 esperan obtener de su experiencia en la junta ejecutiva de TCA? \u00bfQu\u00e9 esperan aportar?<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Gebel:<\/strong> Me comprometer\u00eda a transmitir mi conocimiento de la experiencia y compartir nuestras pr\u00e1cticas recomendadas con la industria, para que la industria siga prosperando, creciendo y mejorando. \u00a1\u201cDevolver\u00e9\u201d a la TCA y a la industria del tilt-up lo que doy!<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Galloway:<\/strong> Espero que mi experiencia en el comit\u00e9 ejecutivo de la TCA refleje la que he tenido en la asociaci\u00f3n desde que asist\u00ed por primera vez a una convenci\u00f3n en 2016. Estoy seguro de que crecer\u00e9 profesional y personalmente al estar rodeado de personas excepcionales a las que les importa mucho lo que hacen y c\u00f3mo lo hacen. No tengo ninguna duda de que desarrollar\u00e9 relaciones que ser\u00e1n cruciales para las decisiones que tome y el futuro al que me llevar\u00e1n esas decisiones. Me esforzar\u00e9 por ayudar e inspirar a otras personas de esta comunidad y tener la misma influencia en sus vidas que la Tilt-Up Concrete Association y sus miembros han tenido en la m\u00eda.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Murray:<\/strong> Lo que espero que se lleven de su experiencia en el comit\u00e9 ejecutivo de la TCA es aumentar sus conocimientos y perspectiva. Al igual que cualquier experiencia en la vida, se aprende escuchando a otros y participando en un di\u00e1logo profundo. Para m\u00ed es un verdadero honor servir en el comit\u00e9 ejecutivo de la TCA e interactuar con un grupo tan devoto de personas de la industria que amo. Lo que espero dar al comit\u00e9 ejecutivo de la TCA es un poco de perspectiva con base en mi experiencia en la industria y mi continua sed de conocimiento.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Mano<\/strong> Lo que espero es crear entusiasmo por los nuevos desarrollos, continuar desarrollando una red de profesionales con un aumento en la membres\u00eda y seguir impulsando la industria para nuestros futuros l\u00edderes.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Conejo<\/strong> Mi experiencia en el comit\u00e9 ejecutivo ha sido tremenda; un peque\u00f1o grupo de l\u00edderes de la industria discutiendo valiosos detalles desde la planificaci\u00f3n conceptual hasta la implementaci\u00f3n de importantes conceptos de negocio. La experiencia que me llevo del comit\u00e9 ejecutivo es el objetivo de hacer que el tilt-up (encofrado y vaciado in situ) sea m\u00e1s que un simple panel de concreto. El comit\u00e9 ejecutivo, dada su composici\u00f3n, nunca se enfoca en el panel de concreto de tilt-up, sino en la idea de que el panel comienza como un concepto general y termina con una multitud de personas valiosas aportando sus retoques para hacerlo un trabajo valioso. El proceso se modifica, se repite y se mejora, sin secretos. Lo que he aportado al comit\u00e9 ejecutivo son mis experiencias desde la perspectiva de un desarrollador hasta la de un subcontratista de concreto, madurando desde un mercado de tilt-up anterior restringido hasta un mercado favorable actual.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Este grupo de l\u00edderes ha contribuido much\u00edsimo para llegar al lugar donde la asociaci\u00f3n se encuentra en el presente y como podr\u00e1 darse cuenta por sus entusiastas respuestas, hay mucho m\u00e1s por venir. Ellos siguen bas\u00e1ndose en el legado de liderazgo que ha sido la columna vertebral de esta asociaci\u00f3n durante d\u00e9cadas y seguir\u00e1 avanzando en esta nueva era. Durante el di\u00e1logo, algunos temas como Tilt Up Leaders for Tomorrow (TILT, L\u00edderes de la industria de tilt-up del ma\u00f1ana) estuvieron entre los compromisos que este comit\u00e9 ejecutivo sigue apoyando y les emociona ver a futuros l\u00edderes de la mesa directiva y el comit\u00e9 ejecutivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si desea m\u00e1s informaci\u00f3n sobre servir en la mesa directiva de la TCA, lo animamos a comunicarse con el director ejecutivo, Mitch Bloomquist, en mbloomquist@tilt-up.org. Si desea obtener m\u00e1s informaci\u00f3n sobre los roles y responsabilidades de la junta directiva de la TCA, as\u00ed como sobre todas las personas que actualmente forman parte de ella, incluidos los cinco miembros del comit\u00e9 ejecutivo que participaron en esta sesi\u00f3n, visite <a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/association\/\">www.tilt-up.org\/asociacion<\/a>\/.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">| Traducci\u00f3n Patrocinada por Nox-Crete Products Group El liderazgo dentro de la Tilt-Up Concrete Association consiste en quince personas que sirven en la mesa directiva. Sirven en t\u00e9rminos rotativos de tres a\u00f1os, renovables hasta <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/08\/26\/conversacion-con-el-comite-ejecutivo-de-la-tca-2\/\" title=\"CONVERSACI\u00d3N CON EL COMIT\u00c9 EJECUTIVO DE LA TCA\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":15745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-15749","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=15749"}],"version-history":[{"count":5,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15749\/revisions"}],"predecessor-version":[{"id":15840,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15749\/revisions\/15840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/15745"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=15749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=15749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=15749"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}