{"id":1563,"date":"2012-05-29T14:21:57","date_gmt":"2012-05-29T19:21:57","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=1563"},"modified":"2015-06-08T02:39:11","modified_gmt":"2015-06-08T07:39:11","slug":"tca-shares-benefits-of-tilt-up-with-architects-in-dc","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2012\/05\/29\/tca-shares-benefits-of-tilt-up-with-architects-in-dc\/","title":{"rendered":"TCA comparte los beneficios del tilt-up con arquitectos en DC"},"content":{"rendered":"<p><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1564\" title=\"AIA_1\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_1.jpg\" alt=\"\" width=\"680\" height=\"340\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_1.jpg 680w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_1-678x340.jpg 678w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_1-300x150.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/a><\/p>\n<p>Por segundo a\u00f1o consecutivo, la Tilt-Up Concrete Association tuvo presencia en la Convenci\u00f3n Nacional y Expo de Dise\u00f1o del Instituto Americano de Arquitectos. El evento de este a\u00f1o se llev\u00f3 a cabo del 17 al 19 de mayo.<sup> <\/sup>en el Walter E. Washington Convention Center en Washington, DC.<\/p>\n<p>La asistencia general al evento fue mayor que la del a\u00f1o pasado. El tr\u00e1fico en el stand de TCA se present\u00f3 de forma intermitente. Durante el per\u00edodo de dos d\u00edas y medio, distribuimos copias de la \u00faltima edici\u00f3n de \u201cTilt-Up Today\u201d y el folleto reci\u00e9n actualizado \u201cTake Pride\u201d. Tambi\u00e9n promocionamos nuestras nuevas publicaciones, \u201cThe Architecture of Tilt-Up\u201d y \u201cThe Construction of Tilt-Up\u201d. Si bien un mayor n\u00famero de personas se llev\u00f3 literatura o se detuvo a echar un vistazo r\u00e1pido, alrededor de sesenta personas se detuvieron para charlar. Como esper\u00e1bamos, las conversaciones se centraron en la resistencia a explosiones, el c\u00f3digo de energ\u00eda y la consecuci\u00f3n de un gran dise\u00f1o con un presupuesto ajustado.<\/p>\n<p><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1567\" title=\"AIA_2\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_2-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_2-225x300.jpg 225w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_2-768x1024.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2012\/05\/AIA_2.jpg 900w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Como usted sabe, la TCA es la fuente principal para las personas que buscan los mejores arquitectos, ingenieros y contratistas de la industria, as\u00ed como lo m\u00e1s reciente en productos, servicios y accesorios de Tilt-Up. Cada mes, transmitimos pistas y proporcionamos referencias para nuestras empresas miembros. En la Convenci\u00f3n Nacional AIA 2012, vimos una gran demanda de este tipo de base de datos de empresas recomendadas.<\/p>\n<p>De las sesenta personas aproximadamente que se detuvieron a hablar en nuestro stand, al menos cinco buscaban espec\u00edficamente un contratista o ingeniero experimentado en Tilt-Up en su \u00e1rea. M\u00e1s de 10 arquitectos que se detuvieron ten\u00edan proyectos de Tilt-Up en fase de dise\u00f1o y cada arquitecto que visit\u00f3 nuestro stand expres\u00f3 inter\u00e9s en dise\u00f1ar con Tilt-Up m\u00e1s en el futuro cercano. Los animamos a involucrar a los contratistas e ingenieros al principio del proyecto para maximizar la eficiencia y ser conscientes de todo el potencial al usar el m\u00e9todo de construcci\u00f3n Tilt-Up.<\/p>\n<p>Adem\u00e1s de interactuar con los asistentes, hubo muchas oportunidades para interactuar con otros expositores. Pudimos reconectar con antiguos miembros, dos de los cuales expresaron inter\u00e9s en volver a unirse a la asociaci\u00f3n. Adicionalmente, dos o tres empresas indicaron que expondr\u00edan en la Convenci\u00f3n Anual de la TCA de 2012 en Florida este oto\u00f1o.<\/p>\n<p>En general, exponer en la feria vali\u00f3 la pena. La Junta Directiva de la TCA sinti\u00f3 firmemente que esta era una audiencia a la que la asociaci\u00f3n necesita mantenerse relevante y sentimos que tenemos una amplia variedad de informaci\u00f3n en muchos formatos para compartir con ellos. La Convenci\u00f3n AIA 2013 se llevar\u00e1 a cabo en Denver, Colorado, otro buen mercado para Tilt-Up.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Por segundo a\u00f1o consecutivo, la Tilt-Up Concrete Association tuvo presencia en la Convenci\u00f3n Nacional y Expo de Dise\u00f1o del Instituto Americano de Arquitectos. El evento de este a\u00f1o se llev\u00f3 a cabo del 17 al <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2012\/05\/29\/tca-shares-benefits-of-tilt-up-with-architects-in-dc\/\" title=\"TCA comparte los beneficios del tilt-up con arquitectos en DC\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":2,"featured_media":1564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[26,63],"class_list":["post-1563","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tca_announcements","tag-architecture","tag-benefits"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=1563"}],"version-history":[{"count":15,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1563\/revisions"}],"predecessor-version":[{"id":7372,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/1563\/revisions\/7372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/1564"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=1563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=1563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=1563"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}