{"id":15367,"date":"2021-02-23T14:50:07","date_gmt":"2021-02-23T19:50:07","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=15367"},"modified":"2025-06-12T14:47:34","modified_gmt":"2025-06-12T19:47:34","slug":"mesa-redonda-cibernetica-de-tca-recibe-nueva-interfaz","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/02\/23\/mesa-redonda-cibernetica-de-tca-recibe-nueva-interfaz\/","title":{"rendered":"LA MESA REDONDA CIBERN\u00c9TICA DE TCA INCORPORA UNA NUEVA INTERFAZ"},"content":{"rendered":"<div style=\"border: 1px solid #dddddd; padding: 0.5em; background-color: #f5f5f5; width: 666px;\">\n<p style=\"text-align: center; color: #808285;\"><a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/02\/23\/tcas-cyber-roundtable-getting-new-interface\/\"><strong>Ingl\u00e9s<\/strong><\/a> | Traducci\u00f3n patrocinada por <a href=\"http:\/\/www.nox-crete.com\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de productos Nox-Crete<\/a><\/p>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Durante a\u00f1os, la Mesa Redonda Cibern\u00e9tica de TCA (l\u00ednea t\u00e9cnica directa) ha sido una herramienta esencial para los profesionales que buscan consejos e informaci\u00f3n para resolver problemas relacionados con proyectos. Las conversaciones sobre lenguaje en contratos, detalles de ingenier\u00eda, revisi\u00f3n de productos, preguntas de recursos humanos, t\u00e9cnicas de construcci\u00f3n, investigaci\u00f3n de materiales y m\u00e1s han resultado en una gran cantidad de conocimientos y experiencias documentadas.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"264\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/02\/Round-Table-r.jpg\" alt=\"\" class=\"wp-image-15362\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/02\/Round-Table-r.jpg 680w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2021\/02\/Round-Table-r-300x116.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora, este valioso material ha sido dif\u00edcil de organizar y casi imposible de acceder despu\u00e9s del hecho. Katt Price, ingeniera profesional de Schaefer, una firma de ingenier\u00eda estructural con oficinas en Ohio y Arizona, ha impulsado el esfuerzo para renovar este servicio desde que asumi\u00f3 el rol de liderazgo en la colaboraci\u00f3n de j\u00f3venes profesionales de la TCA, L\u00edderes de la industria del tilt-up del ma\u00f1ana (TILT, por sus siglas en ingl\u00e9s). \u201cLa L\u00ednea Directa de la TCA es un recurso muy valioso para la comunidad del tilt-up\u201d, dijo Price. \u201cDesde que me un\u00ed a la l\u00ednea directa, he visto un mont\u00f3n de hilos de mensajes electr\u00f3nicos entre los l\u00edderes de la industria de hoy, y me hizo pensar, \u00bfcu\u00e1ntas m\u00e1s conversaciones excelentes ocurrieron antes de que yo me uniese? \u00bfCu\u00e1ntas de mis preguntas ya han sido respondidas por este grupo experimentado?\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante los meses pasados, TILT, en coordinaci\u00f3n con el gerente de TCA para asuntos regulatorios y t\u00e9cnicos, Jim Baty, FACI, FTCA, ha estado documentando las conversaciones anteriores, asignando palabras clave y categoriz\u00e1ndolas para su publicaci\u00f3n. En febrero, el servicio pasar\u00e1 a una nueva plataforma donde estas y todas las discusiones futuras ser\u00e1n m\u00e1s f\u00e1ciles de buscar, interactuar y referenciar. \u201cEstamos ansiosos por salir en vivo pronto\u201d, dijo Price. \u201cHay conversaciones maravillosas escondidas en estos mensajes electr\u00f3nicos que pueden beneficiar a toda la comunidad de tilt-up\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste es un gran avance para este valioso recurso para miembros\u201d, dijo Baty. \u201cSi bien el acceso a colegas experimentados es valioso en el momento, el historial o el legado de las conversaciones no ha sido algo que los miembros pudieran utilizar para investigar. Ahora, no solo podr\u00e1n investigar este archivo de excelente informaci\u00f3n, sino que tambi\u00e9n podr\u00e1n saber con qu\u00e9 frecuencia sus preguntas se comparten con otros, una de las muchas razones excelentes por las que existe una Asociaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso para unirse a la l\u00ednea directa sigue siendo el mismo. Simplemente, visita <a href=\"http:\/\/tilt-up.org\/tilt-uptoday\/es\/\">tilt-up.org<\/a> y haz clic en el bot\u00f3n \u2018unirse\u2019. Requiere membres\u00eda de la TCA.<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">English | Translation Sponsored by Nox-Crete Products Group: Por a\u00f1os la Mesa Redonda Cibern\u00e9tica de TCA (l\u00ednea t\u00e9cnica directa) ha sido una herramienta esencial para los profesionales que buscan consejos e informaci\u00f3n para resolver problemas. <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2021\/02\/23\/mesa-redonda-cibernetica-de-tca-recibe-nueva-interfaz\/\" title=\"LA MESA REDONDA CIBERN\u00c9TICA DE TCA INCORPORA UNA NUEVA INTERFAZ\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":15362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-15367","post","type-post","status-publish","format-standard","has-post-thumbnail","category-en-espanol"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=15367"}],"version-history":[{"count":3,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15367\/revisions"}],"predecessor-version":[{"id":15397,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15367\/revisions\/15397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/15362"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=15367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=15367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=15367"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}