{"id":15257,"date":"2020-12-23T10:42:11","date_gmt":"2020-12-23T15:42:11","guid":{"rendered":"http:\/\/72.167.124.155\/tilt-uptoday\/?p=15257"},"modified":"2025-10-27T15:32:53","modified_gmt":"2025-10-27T20:32:53","slug":"2020-tilt-up-convention-and-expo","status":"publish","type":"post","link":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2020\/12\/23\/2020-tilt-up-convention-and-expo\/","title":{"rendered":"Convenci\u00f3n y Expo Tilt-Up 2020"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>De California a Nueva Jersey<\/strong>, Florida a Colorado y en cualquier lugar intermedio, la Tilt-Up Convention and Expo ha reunido a la industria durante 3 d\u00edas de educaci\u00f3n, networking, premios, exhibiciones, demostraciones, recorridos y \u00a1mucho m\u00e1s! Como todos sabemos, el 2020 ha presentado desaf\u00edos que han abrumado a due\u00f1os de negocios y empleados en todo el mundo, ha alterado la forma en que operamos y ha paralizado por completo nuestra capacidad de reunirnos\u2026 \u00bfo no?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-1-1-1024x556.jpg\" alt=\"\" class=\"wp-image-15265\" width=\"680\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-1-1-1024x556.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-1-1-300x163.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-1-1-768x417.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-1-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Convenci\u00f3n y Expo Tilt-Up 2020 reuni\u00f3 a la industria como nunca antes. En asociaci\u00f3n con White Cap, Meadow Burke y numerosos otros patrocinadores del evento, el evento de este a\u00f1o present\u00f3 a los asistentes un mundo completamente nuevo, The Aggregate. The Aggregate es un destino de eventos virtuales revolucionario basado en avatares, dise\u00f1ado para reuniones tanto grandes como peque\u00f1as. Completo con numerosos auditorios, aulas, salas de reuniones, espacio de oficinas, una playa, un sal\u00f3n de exposiciones expandible y mucho m\u00e1s, The Aggregate es una soluci\u00f3n llave en mano para una experiencia de evento verdaderamente virtual y nos permiti\u00f3 reunirnos a pesar de los desaf\u00edos que este a\u00f1o ha presentado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste a\u00f1o, no pudimos estar juntos\u201d, dijo Mitch Bloomquist, director ejecutivo de la Tilt-Up Concrete Association (TCA). \u201cPero estuvimos\u201d, dijo Bloomquist. \u201cFuimos la comunidad. A pesar de estar dispersos por todo el mundo. A pesar de la implacable influencia de esta pandemia. A pesar de las dificultades financieras. Fuimos la comunidad\u201d.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presentado por White Cap y Meadow Burke, la Convenci\u00f3n y Expo Tilt-Up 2020 produjo el mayor n\u00famero de inscripciones hasta la fecha y reuni\u00f3 exitosamente a la comunidad tilt-up, virtualmente, durante una semana completa de educaci\u00f3n, exhibiciones, recorridos por obras, premios, networking y mucho m\u00e1s. \u201cEsta comunidad es nuestro activo m\u00e1s preciado\u201d, dijo Bloomquist. \u201cLa educaci\u00f3n, la innovaci\u00f3n y el crecimiento provienen de ella, y no existen sin ella\u201d.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Completo con m\u00e1s de 20 horas de educaci\u00f3n, 6 recorridos virtuales por obras, 11 demostraciones de productos en vivo, numerosas sesiones bajo demanda, un programa de premios y una sala de exposiciones repleta de los \u00faltimos productos y tecnolog\u00edas que la industria tiene para ofrecer, el evento virtual de este a\u00f1o atrajo a m\u00e1s de 800 asistentes de casi 250 empresas de todo el mundo. Con la plataforma basada en avatares de The Aggregate, los asistentes pudieron tener una presencia real en el evento y comunicarse efectivamente entre s\u00ed mientras deambulaban desde el auditorio hasta la sala de exposiciones, y de las aulas a la playa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAl organizar la Convenci\u00f3n y Expo en este entorno virtual interactivo, la TCA ofreci\u00f3 una soluci\u00f3n maravillosa a la pregunta de c\u00f3mo reunirnos en este a\u00f1o desafiante\u201d, dijo Rick Galloway, vicepresidente ejecutivo de Martin Construction. \u201cOrganizar el evento de esta manera llen\u00f3 un vac\u00edo importante, al permitir que las personas se reunieran \u2018cara a cara\u2019 como individuos, y fueran parte de \u2018grupos\u2019 interactivos m\u00e1s grandes a trav\u00e9s de avatares\u201d, dijo Galloway. \u201cEsto nos dio el sentido de comunidad que todos amamos de la TCA, al tiempo que respetaba la necesidad de mantener a todos a salvo\u201d.\u201d<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-2-1024x612.jpg\" alt=\"\" class=\"wp-image-15266\" width=\"680\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-2-1024x612.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-2-300x179.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-2-768x459.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El evento comenz\u00f3 el lunes 5 de octubre con varias clases de orientaci\u00f3n que permitieron a los asistentes profundizar en la plataforma y aprender m\u00e1s sobre la capacidad de su avatar para comunicarse y navegar por el campus virtual. Tambi\u00e9n hubo una carrera, partidos de f\u00fatbol y una serie de visitas virtuales a lugares de trabajo y sesiones a pedido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada educativa comenz\u00f3 el segundo d\u00eda e incluy\u00f3 una conferencia magistral de Barclay Gebel de Concrete Strategies, y exhibiciones dedicadas a ahorrar tiempo, dinero y vidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tercer d\u00eda continu\u00f3 con educaci\u00f3n valiosa, una conferencia magistral patrocinada por Innovative Structural Solutions, horas de exhibici\u00f3n dedicadas a acabados arquitect\u00f3nicos, y concluy\u00f3 con la Gala de Premios Tilt-Up 2020, seguida de la Fiesta posterior del Presidente en la playa, con entretenimiento de The Pork Tornados.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"http:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-3-1024x612.jpg\" alt=\"\" class=\"wp-image-15267\" width=\"680\" srcset=\"https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-3-1024x612.jpg 1024w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-3-300x179.jpg 300w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-3-768x459.jpg 768w, https:\/\/tilt-up.org\/tilt-uptoday\/wp-content\/uploads\/2020\/12\/Screen-Shot-3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La educaci\u00f3n se reanud\u00f3 el cuarto d\u00eda con una conferencia magistral de Jeffrey Brown de Powers Brown Architecture, y 11 empresas expositoras presentaron demostraciones de productos en el vest\u00edbulo del sal\u00f3n de exposiciones, atrayendo a asistentes de todo el mundo para comprender mejor sus productos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento concluy\u00f3 el quinto d\u00eda y fue dise\u00f1ado espec\u00edficamente para asistentes internacionales. Tilt-Up 101 se present\u00f3 en espa\u00f1ol, y tambi\u00e9n se anim\u00f3 a los expositores a tener personal biling\u00fce disponible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00a1Qu\u00e9 gran semana! Justo la chispa que necesitaba para salir de esta nube\u201d, dijo Raymond Elias, gerente de operaciones de concreto en Oltmans Construction Co. \u201cEs muy refrescante estar entre personas que hablan mi idioma, que entienden los desaf\u00edos y de quienes puedo seguir aprendiendo nuevas ideas, innovaciones y tendencias\u201d.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque todos esperamos con ansias poder reunirnos en persona nuevamente, es innegable que el evento de este a\u00f1o demostr\u00f3 la importancia de estar presente. Independientemente de las circunstancias, las empresas y los profesionales m\u00e1s influyentes de la industria estuvieron presentes con una mente abierta y deseosos de aprender. \u201cAhora lo saben, vale la pena\u201d, dijo Bloomquist. \u201cEs inspirador. Es energizante. Ahora lo saben, no se lo pueden perder\u201d.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n sobre la Convenci\u00f3n y Expo Tilt-Up 2020, visite <a href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/events\/\">www.tilt-up.org\/eventos<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00a1Gracias a los patrocinadores de 2020!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PATROCINADORES<\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Patrocinador Principal<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Leviat&nbsp;<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gorra blanca<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>V\u00eda de construcci\u00f3n<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Materiales de Construcci\u00f3n Primarios&nbsp;<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seretta Construction, Inc.&nbsp;<strong>CC<\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Dise\u00f1o de pista<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Dayton Superior Corporation&nbsp;<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Productos de Alambre Insteel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Needham DBS&nbsp;<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Gala de Premiaci\u00f3n Tilt-Up<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nox-Crete, Inc.&nbsp;<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>D\u00eda de demostraci\u00f3n<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Gorra blanca<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Tilt-Up 101<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Gorra blanca<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Ponente principal<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Soluciones Estructurales Innovadoras<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Socio Educativo<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Soluciones Estructurales Innovadoras<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Patrocinador del conserje<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Connect-EZ\u00a0<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GluDown, Inc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Innovative Brick Systems, LLC\u00a0<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soluciones Estructurales Innovadoras<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MAX USA CORP.\u00a0<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Recepci\u00f3n Internacional<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Materiales de Construcci\u00f3n Primarios <strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong>\u00a0<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Excursiones<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Materiales de Construcci\u00f3n Primarios\u00a0<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soluciones Estructurales Innovadoras <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"12\" height=\"12\" src=\"\">&nbsp;<strong>CC<\/strong>\u2013 Empresa certificada&nbsp;&nbsp;&nbsp;&nbsp;<img loading=\"lazy\" decoding=\"async\" width=\"12\" height=\"12\" src=\"\">&nbsp;<strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">SM<\/span><\/strong>\u2013 Miembro de apoyo<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">De California a Nueva Jersey, de Florida a Colorado y a todos los puntos intermedios, la Convenci\u00f3n y Expo Tilt-Up ha unido a la industria durante 3 d\u00edas de educaci\u00f3n, networking, premios, exposiciones, demostraciones, recorridos y mucho m\u00e1s. <a class=\"mh-excerpt-more\" href=\"https:\/\/tilt-up.org\/tilt-uptoday\/es\/2020\/12\/23\/2020-tilt-up-convention-and-expo\/\" title=\"Convenci\u00f3n y Expo Tilt-Up 2020\"> Leer m\u00e1s\u2026<\/a><\/div>","protected":false},"author":6,"featured_media":15267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[375],"tags":[],"class_list":["post-15257","post","type-post","status-publish","format-standard","has-post-thumbnail","category-community-culture"],"primary_market_category":null,"_links":{"self":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/comments?post=15257"}],"version-history":[{"count":12,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15257\/revisions"}],"predecessor-version":[{"id":15274,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/posts\/15257\/revisions\/15274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media\/15267"}],"wp:attachment":[{"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/media?parent=15257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/categories?post=15257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tilt-up.org\/tilt-uptoday\/es\/wp-json\/wp\/v2\/tags?post=15257"}],"curies":[{"name":"la hora de","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}